{"id":36679,"date":"2024-11-12T13:04:01","date_gmt":"2024-11-12T16:04:01","guid":{"rendered":"https:\/\/newsinfoco.com.br\/inicio\/?p=36679"},"modified":"2024-11-12T13:05:47","modified_gmt":"2024-11-12T16:05:47","slug":"nova-jornada-de-trabalho-e-criticada-por-lideranca-dos-empresarios-de-bares-e-restaurantes","status":"publish","type":"post","link":"https:\/\/newsinfoco.com.br\/inicio\/nova-jornada-de-trabalho-e-criticada-por-lideranca-dos-empresarios-de-bares-e-restaurantes\/","title":{"rendered":"Nova jornada de trabalho \u00e9 criticada por lideran\u00e7a dos empres\u00e1rios de bares e restaurantes"},"content":{"rendered":"<p>O fim da escala de trabalho 6 X 1, na qual o descanso remunerado ocorre apenas aos domingos, \u00e9 uma \u201cideia estapaf\u00fardia\u201d na opini\u00e3o de Paulo Solmucci J\u00fanior, presidente executivo da Abrasel (Associa\u00e7\u00e3o Brasileira de Bares e Restaurantes).<\/p>\n<p>Segundo ele, a PEC (proposta de emenda \u00e0 Constitui\u00e7\u00e3o) que prop\u00f5e a mudan\u00e7a n\u00e3o dever\u00e1 ser aprovada. \u201cN\u00e3o vejo chance de uma ideia estapaf\u00fardia dessa prosperar\u201d, disse \u00e0 Folha. Mas, caso passe pela C\u00e2mara dos Deputados e pelo Senado, a medida poder\u00e1 elevar os pre\u00e7os de produtos e servi\u00e7os em 15%.<\/p><div class=\"newsi-conteudo_19\" id=\"newsi-1066234461\"><a href=\"https:\/\/www.instagram.com\/prefeituraalagoinhas?igsh=YzgzdDJ1bWR3aWI4\" aria-label=\"SAVE_20251006_221555\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg\" alt=\"\"  srcset=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg 1140w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-300x52.jpg 300w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1024x177.jpg 1024w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-768x133.jpg 768w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-600x104.jpg 600w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-696x120.jpg 696w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1068x185.jpg 1068w\" sizes=\"(max-width: 1140px) 100vw, 1140px\" width=\"1140\" height=\"197\"   \/><\/a><\/div>\n<p>A redu\u00e7\u00e3o de jornada est\u00e1 sendo proposta pela deputada Erika Hilton (PSOL-SP), que busca assinaturas para dar andamento \u00e0 PEC. S\u00e3o necess\u00e1rias 171 assinaturas dos 513 deputados. At\u00e9 a noite desta segunda-feira (11), havia 132.<\/p>\n<p>A altera\u00e7\u00e3o instituiria jornada semanal de 36 horas ante a jornada atual, de 44 horas semanais.<\/p>\n<p>Para Solmucci J\u00fanior, o trabalhador j\u00e1 tem a op\u00e7\u00e3o de escolher outras escalas, se n\u00e3o quiser trabalhar as 44 horas semanais previstas pela Constitui\u00e7\u00e3o Federal e pela CLT (Consolida\u00e7\u00e3o das Leis do Trabalho).<\/p>\n<p>O empres\u00e1rio afirma ainda que a demanda por bares e restaurantes abertos sete dias por semana vem dos clientes e n\u00e3o atend\u00ea-los \u00e9 um problema econ\u00f4mico.<\/p>\n<p>\u201cTodo mundo quer bar e restaurante dispon\u00edvel a semana inteira, e querem a custo baixo. A\u00ed voc\u00ea v\u00ea as pessoas querendo inviabilizar para o consumidor. E j\u00e1 estamos com dificuldades enormes com trabalhadores\u201d, afirma.<\/p>\n<p>Solmucci afirma que a quest\u00e3o j\u00e1 est\u00e1 regulamentada e pacificada tanto na Constitui\u00e7\u00e3o quanto na CLT e, por isso, n\u00e3o precisa de uma emenda constitucional.<\/p>\n<p>\u201cA Abrasel integra a uni\u00e3o nacional das entidades de com\u00e9rcio e servi\u00e7os onde est\u00e3o as maiores entidades, representada por uma frente parlamentar muito forte. Tenho certeza que essa frente de quase 300 parlamentares n\u00e3o vai deixar prosperar.\u201d<\/p>\n<p>Dentro da pr\u00f3pria associa\u00e7\u00e3o, no entanto, a medida divide opini\u00f5es. Para alguns diretores, a falta de m\u00e3o de obra \u00e9 uma das justificativas para a mudan\u00e7a na escala de trabalho, com mais folgas aos trabalhadores, e automatiza\u00e7\u00e3o maior dos servi\u00e7os.<\/p>\n<p>\u201cAo meu ver, no processo civilizat\u00f3rio, a gente deveria estar indo para uma economia em que as pessoas trabalhassem menos, J\u00e1 temos cada vez mais m\u00e1quinas que trabalham por n\u00f3s. O problema \u00e9 produtividade, a concorr\u00eancia e uma economia subdesenvolvida, que patina\u201d, diz o advogado Percival Maricato, diretor da Abrasel.<\/p>\n<p>Leonel Paim, presidente da AbraselSP (Associa\u00e7\u00e3o Brasileira de Bares e Restaurantes de SP), afirma que, hoje h\u00e1 outras op\u00e7\u00f5es de trabalho, com mais liberdade para o profissional, e isso pode estar afastando os trabalhadores da \u00e1rea de bares e restaurante.<\/p>\n<p>Paim trata ainda das diferen\u00e7as de atividades dependendo da localidade. Segundo ele, estabelecimentos em cidades tur\u00edsticas j\u00e1 n\u00e3o abrem de segunda a quarta, e t\u00eam funcionamento de quinta a domingo.<\/p>\n<p>Maricato acredita que o Congresso pode chegar a um meio-termo, com a redu\u00e7\u00e3o da jornada de 44 horas semanais para 40 horas, instituindo a jornada 5 X 2 para todos os trabalhadores, como j\u00e1 h\u00e1 em muitos setores. E, s\u00f3 depois, evoluir para os quatro dias de trabalho e tr\u00eas de descanso, como em pa\u00edses da Europa.<\/p>\n<p>\u201cEst\u00e1 na hora de a gente conseguir um equil\u00edbrio\u201d, diz.<\/p>\n<p>O texto da PEC prop\u00f5e alterar o artigo 7\u00ba da Constitui\u00e7\u00e3o, no inciso 8, que trata sobre a jornada de trabalho. A sugest\u00e3o \u00e9 de jornada de quatro dias semanais, medida adotada em alguns pa\u00edses do mundo e que chegou a ser testada no Brasil por algumas empresas.<\/p>\n<p>O trecho passaria a vigorar da seguinte forma: \u201cDura\u00e7\u00e3o do trabalho normal n\u00e3o superior a oito horas di\u00e1rias e trinta e seis horas semanais, com jornada de trabalho de quatro dias por semana, facultada a compensa\u00e7\u00e3o de hor\u00e1rios e a redu\u00e7\u00e3o de jornada, mediante acordo ou conven\u00e7\u00e3o coletiva de trabalho\u201d.<\/p>\n<p>Hoje, a Constitui\u00e7\u00e3o determina jornada de trabalho limitada a \u201coito horas di\u00e1rias e quarenta e quatro semanais, facultada a compensa\u00e7\u00e3o de hor\u00e1rios e a redu\u00e7\u00e3o da jornada, mediante acordo ou conven\u00e7\u00e3o coletiva de trabalho\u201d.<\/p>\n<p>Em geral, boa parte dos trabalhadores t\u00eam escala 5 X 2, com exce\u00e7\u00e3o de atividades especiais, autorizadas a funcionar aos domingos. Na jornada de cinco dias de trabalho, \u00e9 necess\u00e1rio cumprir mais horas di\u00e1rias do que as oito necess\u00e1rias, para n\u00e3o precisar ir \u00e0 empresa aos s\u00e1bados.<\/p>\n<p>A deputada Erika Hilton protocolou a medida na C\u00e2mara em 1\u00ba de Maio, quando se celebra o Dia do Trabalho no Brasil e no mundo, ocasi\u00e3o na qual tamb\u00e9m a levou ao ministro do Trabalho, Luiz Marinho.<\/p>\n<p>A proposta foi apresentada a ela pelo Movimento VAT (Vida Al\u00e9m do Trabalho), encabe\u00e7ado pelo rec\u00e9m-eleito vereador Rick Azevedo (PSOL-RJ).<\/p>\n<p>\u201cAbracei de imediato por compreender ser um debate importante, relevante\u201d, disse a deputada \u00e0 Folha.<\/p>\n<p>Fonte: Pol\u00edtica Livre<\/p>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='Nova jornada de trabalho \u00e9 criticada por lideran\u00e7a dos empres\u00e1rios de bares e restaurantes' data-link='https:\/\/newsinfoco.com.br\/inicio\/nova-jornada-de-trabalho-e-criticada-por-lideranca-dos-empresarios-de-bares-e-restaurantes\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>O fim da escala de trabalho 6 X 1, na qual o descanso remunerado ocorre apenas aos domingos, \u00e9 uma \u201cideia estapaf\u00fardia\u201d na opini\u00e3o de Paulo Solmucci J\u00fanior, presidente executivo da Abrasel (Associa\u00e7\u00e3o Brasileira de Bares e Restaurantes). Segundo ele, a PEC (proposta de emenda \u00e0 Constitui\u00e7\u00e3o) que prop\u00f5e a mudan\u00e7a n\u00e3o dever\u00e1 ser aprovada. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":36680,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[21],"tags":[],"class_list":["post-36679","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/36679","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/comments?post=36679"}],"version-history":[{"count":2,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/36679\/revisions"}],"predecessor-version":[{"id":36682,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/36679\/revisions\/36682"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media\/36680"}],"wp:attachment":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media?parent=36679"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/categories?post=36679"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/tags?post=36679"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}