{"id":36854,"date":"2024-11-19T13:32:54","date_gmt":"2024-11-19T16:32:54","guid":{"rendered":"https:\/\/newsinfoco.com.br\/inicio\/?p=36854"},"modified":"2024-11-19T13:51:19","modified_gmt":"2024-11-19T16:51:19","slug":"olodum-homenageia-zumbi-como-parte-das-atividades-do-dia-da-consciencia-negra","status":"publish","type":"post","link":"https:\/\/newsinfoco.com.br\/inicio\/olodum-homenageia-zumbi-como-parte-das-atividades-do-dia-da-consciencia-negra\/","title":{"rendered":"Olodum homenageia Zumbi como parte das atividades do dia da Consci\u00eancia Negra"},"content":{"rendered":"<p>A Casa do Olodum, no Pelourinho, ser\u00e1 palco da abertura das comemora\u00e7\u00f5es do Dia Nacional da Consci\u00eancia Negra, nesta ter\u00e7a-feira (19), \u00e0s 19h. A iniciativa integra a programa\u00e7\u00e3o do Salvador Capital Afro, promovida pela Secretaria de Cultura e Turismo (Secult), em homenagem ao m\u00eas da Consci\u00eancia Negra. O evento celebra a mem\u00f3ria de Zumbi dos Palmares e reafirma a luta e resist\u00eancia da comunidade afro-brasileira.<\/p>\n<p>\u201cVamos celebrar, com grande honra, o legado, a mem\u00f3ria e a luta de Zumbi pela liberta\u00e7\u00e3o do povo negro\u201d, afirmou Jorginho Rodrigues, presidente-executivo do Olodum. Ele destacou a import\u00e2ncia simb\u00f3lica da Casa do Olodum, um espa\u00e7o reconhecido internacionalmente na luta contra o racismo e a discrimina\u00e7\u00e3o. \u201cA poderosa percuss\u00e3o do Olodum e seus cantores far\u00e3o uma apresenta\u00e7\u00e3o hist\u00f3rica e emocionante para a popula\u00e7\u00e3o\u201d, completou.<\/p><div class=\"newsi-conteudo_19\" id=\"newsi-38738408\"><a href=\"https:\/\/www.instagram.com\/prefeituraalagoinhas?igsh=YzgzdDJ1bWR3aWI4\" aria-label=\"SAVE_20251006_221555\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg\" alt=\"\"  srcset=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg 1140w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-300x52.jpg 300w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1024x177.jpg 1024w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-768x133.jpg 768w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-600x104.jpg 600w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-696x120.jpg 696w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1068x185.jpg 1068w\" sizes=\"(max-width: 1140px) 100vw, 1140px\" width=\"1140\" height=\"197\"   \/><\/a><\/div>\n<p>O grupo, que h\u00e1 40 anos promove o Festiquilombo, utiliza o m\u00eas de novembro para resgatar a hist\u00f3ria da resist\u00eancia negra e celebrar o 20 de novembro, data da morte de Zumbi. O espet\u00e1culo desta noite incluir\u00e1 can\u00e7\u00f5es que exaltam a figura de Zumbi e reafirmam o compromisso do Olodum contra a discrimina\u00e7\u00e3o e a viol\u00eancia.<\/p>\n<p>Al\u00e9m do evento no Pelourinho, a programa\u00e7\u00e3o do Salvador Capital Afro inclui shows e atividades culturais em diversos pontos da cidade. Na quarta-feira (20), a cantora Luedji Luna apresenta o espet\u00e1culo Luedji Luna Canta Sade, no Largo da Mariquita, no Rio Vermelho. O show homenageia a cantora nigeriana Sade Adu com sucessos como No Ordinary Love e Smooth Operator.<\/p>\n<div>\n<div>\n<div class=\"trv-player-container\">\n<div class=\"trv-wrapper\">\n<div id=\"br_video_player_0ce2cda09b50e6b07560356e396b169dc3c659f9\" class=\"trvd_video_player trvdinstream\">\n<div class=\"media-player\">\n<div class=\"trv-video\">\n<div id=\"truvid_ima_container67604\" class=\"truvid_ima_container\">\n<div>\n<div>\n<div>\n<p>No dia 23, o Espa\u00e7o Cultural da Barroquinha recebe uma edi\u00e7\u00e3o especial do Samba \u1e62\u00edb\u00ed D\u00fad\u00fa, celebrando quatro anos do projeto. At\u00e9 o final do m\u00eas, o p\u00fablico poder\u00e1 conferir apresenta\u00e7\u00f5es do projeto AfroCortejo, caminhadas percussivas no Centro Hist\u00f3rico, entre outras atra\u00e7\u00f5es.<\/p>\n<p>A programa\u00e7\u00e3o completa est\u00e1 dispon\u00edvel no\u00a0<a href=\"http:\/\/www.salvadordabahia.com\/novembro\" target=\"_blank\" rel=\"noopener\">site oficial da Secult<\/a>.<\/p>\n<p>Fonte: Bahia.ba<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='Olodum homenageia Zumbi como parte das atividades do dia da Consci\u00eancia Negra' data-link='https:\/\/newsinfoco.com.br\/inicio\/olodum-homenageia-zumbi-como-parte-das-atividades-do-dia-da-consciencia-negra\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>A Casa do Olodum, no Pelourinho, ser\u00e1 palco da abertura das comemora\u00e7\u00f5es do Dia Nacional da Consci\u00eancia Negra, nesta ter\u00e7a-feira (19), \u00e0s 19h. A iniciativa integra a programa\u00e7\u00e3o do Salvador Capital Afro, promovida pela Secretaria de Cultura e Turismo (Secult), em homenagem ao m\u00eas da Consci\u00eancia Negra. O evento celebra a mem\u00f3ria de Zumbi dos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":36855,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[19],"tags":[],"class_list":["post-36854","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bahia"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/36854","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/comments?post=36854"}],"version-history":[{"count":2,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/36854\/revisions"}],"predecessor-version":[{"id":36861,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/36854\/revisions\/36861"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media\/36855"}],"wp:attachment":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media?parent=36854"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/categories?post=36854"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/tags?post=36854"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}