{"id":36898,"date":"2024-11-21T13:11:38","date_gmt":"2024-11-21T16:11:38","guid":{"rendered":"https:\/\/newsinfoco.com.br\/inicio\/?p=36898"},"modified":"2024-11-21T13:11:38","modified_gmt":"2024-11-21T16:11:38","slug":"orquestra-afrodiasporica-faz-shows-inspirados-na-ancestralidade-e-na-multiculturalidade","status":"publish","type":"post","link":"https:\/\/newsinfoco.com.br\/inicio\/orquestra-afrodiasporica-faz-shows-inspirados-na-ancestralidade-e-na-multiculturalidade\/","title":{"rendered":"Orquestra Afrodiasp\u00f3rica faz shows inspirados na ancestralidade e na multiculturalidade"},"content":{"rendered":"<p>O violinista M\u00e1rio Soares e sua Orquestra Afrodiasp\u00f3rica v\u00e3o se apresentar no pr\u00f3ximo s\u00e1bado, 23, no Mirante do Solar, em\u00a0<a href=\"https:\/\/atarde.com.br\/?q=Itaparica&amp;d=1\" target=\"_blank\" rel=\"noopener\" data-rel-defined=\"\">Itaparica<\/a>, e no domingo, 24, na Casa Rosa, no\u00a0<a href=\"https:\/\/atarde.com.br\/?q=Rio+Vermelho&amp;d=1\" target=\"_blank\" rel=\"noopener\" data-rel-defined=\"\">Rio Vermelho, em Salvador.<\/a>\u00a0Os shows v\u00e3o celebrar a ancestralidade e pluralidade cultural brasileira.<\/p>\n<p>Em Salvador ser\u00e3o dois shows, \u00e0s 17h e 20h, que contam com a participa\u00e7\u00e3o da artista e percussionista Lan Lanh. Os ingressos s\u00e3o gratuitos e podem ser adquiridos atrav\u00e9s do\u00a0<a href=\"https:\/\/bileto.sympla.com.br\/event\/100896\/d\/289691\/s\/1972451?share_id=1-copiarlink\" target=\"_blank\" rel=\"noopener\" data-rel-defined=\"\">Sympla<\/a>.<\/p><div class=\"newsi-conteudo_19\" id=\"newsi-1833504090\"><a href=\"https:\/\/www.instagram.com\/prefeituraalagoinhas?igsh=YzgzdDJ1bWR3aWI4\" aria-label=\"SAVE_20251006_221555\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg\" alt=\"\"  srcset=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg 1140w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-300x52.jpg 300w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1024x177.jpg 1024w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-768x133.jpg 768w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-600x104.jpg 600w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-696x120.jpg 696w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1068x185.jpg 1068w\" sizes=\"(max-width: 1140px) 100vw, 1140px\" width=\"1140\" height=\"197\"   \/><\/a><\/div>\n<p>O repert\u00f3rio vai incluir can\u00e7\u00f5es autorais, pe\u00e7as de importantes multi-instrumentistas como Villa-Lobos e\u00a0<a href=\"https:\/\/atarde.com.br\/?q=Letieres+Leite&amp;d=1\" target=\"_blank\" rel=\"noopener\" data-rel-defined=\"\">Letieres Leite<\/a>, al\u00e9m de can\u00e7\u00f5es consagradas popularmente como \u2018Cordeiro de Nan\u00e3\u2019, \u2018\u2060Lamento Sertanejo\u2019, \u2018S\u2060amba da minha Terra\u2019 e \u2018Festa do Interior\u2019.<\/p>\n<p>\u201cQueremos transmitir a hist\u00f3ria e a riqueza cultural da Bahia e do nosso povo, mostrando que as diferen\u00e7as existem para enriquecer o mundo, n\u00e3o para nos separar. A Orquestra Afrodiasp\u00f3rica \u00e9 a express\u00e3o dessa uni\u00e3o que atrav\u00e9s da m\u00fasica caracteriza a identidade brasileira\u201d, ressalta M\u00e1rio Soares.<\/p>\n<p>Outro destaque do show ser\u00e1 a apresenta\u00e7\u00e3o do \u2018Hino do Senhor do Bonfim\u2019, que contar\u00e1 com a participa\u00e7\u00e3o da artista e percussionista Lan Lanh no berimbau e de M\u00e1rio no violino. Lan Lanh tamb\u00e9m participa do show tocando cajon e outros instrumentos percussivos.<\/p>\n<p>Fonte: A Tarde<\/p>\n<div id=\"dmh-h-par2\" class=\"jba filled\" data-google-query-id=\"CJ2kkOvm7YkDFalI3QId2hsvpw\"><\/div>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='Orquestra Afrodiasp\u00f3rica faz shows inspirados na ancestralidade e na multiculturalidade' data-link='https:\/\/newsinfoco.com.br\/inicio\/orquestra-afrodiasporica-faz-shows-inspirados-na-ancestralidade-e-na-multiculturalidade\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>O violinista M\u00e1rio Soares e sua Orquestra Afrodiasp\u00f3rica v\u00e3o se apresentar no pr\u00f3ximo s\u00e1bado, 23, no Mirante do Solar, em\u00a0Itaparica, e no domingo, 24, na Casa Rosa, no\u00a0Rio Vermelho, em Salvador.\u00a0Os shows v\u00e3o celebrar a ancestralidade e pluralidade cultural brasileira. Em Salvador ser\u00e3o dois shows, \u00e0s 17h e 20h, que contam com a participa\u00e7\u00e3o da [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":36899,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[19],"tags":[],"class_list":["post-36898","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bahia"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/36898","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/comments?post=36898"}],"version-history":[{"count":1,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/36898\/revisions"}],"predecessor-version":[{"id":36900,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/36898\/revisions\/36900"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media\/36899"}],"wp:attachment":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media?parent=36898"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/categories?post=36898"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/tags?post=36898"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}