{"id":37227,"date":"2024-12-05T14:01:27","date_gmt":"2024-12-05T17:01:27","guid":{"rendered":"https:\/\/newsinfoco.com.br\/inicio\/?p=37227"},"modified":"2024-12-05T14:05:35","modified_gmt":"2024-12-05T17:05:35","slug":"37227-2","status":"publish","type":"post","link":"https:\/\/newsinfoco.com.br\/inicio\/37227-2\/","title":{"rendered":"Pesquisa mostra que 58,3% dos baianos vivem sem acesso \u00e0 rede de esgoto"},"content":{"rendered":"<p>Uma pesquisa feita pela IFAT Brasil com a Pezco Economics e a Resolux Company revela os desafios da Bahia no saneamento b\u00e1sico: 58,3% da popula\u00e7\u00e3o do estado n\u00e3o tem acesso \u00e0 rede de esgoto, enquanto 19,4% n\u00e3o s\u00e3o contemplados com rede de \u00e1gua.<\/p>\n<p>O levantamento aponta, ainda, outras defici\u00eancias, como a perda de \u00e1gua nas redes, que chega a 42,5% no estado. Al\u00e9m disso, apenas 48,8% do esgoto gerado \u00e9 tratado. Do total de esgoto coletado, o percentual de tratamento \u00e9 maior: 80,4%.<\/p><div class=\"newsi-conteudo_19\" id=\"newsi-2163079242\"><a href=\"https:\/\/www.instagram.com\/prefeituraalagoinhas?igsh=YzgzdDJ1bWR3aWI4\" aria-label=\"SAVE_20251006_221555\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg\" alt=\"\"  srcset=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg 1140w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-300x52.jpg 300w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1024x177.jpg 1024w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-768x133.jpg 768w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-600x104.jpg 600w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-696x120.jpg 696w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1068x185.jpg 1068w\" sizes=\"(max-width: 1140px) 100vw, 1140px\" width=\"1140\" height=\"197\"   \/><\/a><\/div>\n<p>O estudo tamb\u00e9m traz dados como cobertura de pavimenta\u00e7\u00e3o e meio-fio nas \u00e1reas urbanas (59,8%), cobertura de vias p\u00fablicas com redes ou canais pluviais subterr\u00e2neos nas \u00e1reas urbanas (17,9%) e cobertura dos servi\u00e7os de coleta de res\u00edduos domiciliares (84,1%).<\/p>\n<p>A base das informa\u00e7\u00f5es s\u00e3o projetos de PPP\u2019s, bancos modeladores, planos de expans\u00e3o de concession\u00e1rias e operadores de servi\u00e7o.<\/p>\n<p><strong>Investimentos<\/strong><\/p>\n<p>A pesquisa faz o raio-X de estados, grandes regi\u00f5es e pa\u00eds. No Brasil, at\u00e9 2040, a previs\u00e3o \u00e9 a de que R$ 387 bilh\u00f5es sejam investidos em \u00e1gua e esgoto. O valor revela um ambiente mais favor\u00e1vel para investimentos no setor em compara\u00e7\u00e3o a cen\u00e1rios passados, por\u00e9m, ainda aponta um d\u00e9ficit em rela\u00e7\u00e3o \u00e0s estimativas necess\u00e1rias para a universaliza\u00e7\u00e3o at\u00e9 2033.<\/p>\n<p>O levantamento aponta que uma m\u00e9dia de R$ 25 bi anuais ser\u00e3o empregados nos pr\u00f3ximos tr\u00eas anos, considerando uma abordagem bottom-up, ou seja, que considera caracter\u00edsticas espec\u00edficas, n\u00e3o macroecon\u00f4micas, de projetos leiloados, em fase de estudo, em consultas p\u00fablicas a bancos e recursos previstos a estruturas fixas no pa\u00eds.<\/p>\n<p>Dos R$ 387 bilh\u00f5es, 42% ser\u00e3o destinados aos planos de expans\u00e3o e investimento das operadoras e 35% est\u00e3o contratados em concess\u00f5es e PPP\u2019s, com desembolso previsto at\u00e9 2040. Outros 21% est\u00e3o em etapa de estudo e modelagem na linha de projetos das ag\u00eancias financeiras e bancos modeladores. E 2% est\u00e3o em consulta p\u00fablica e edital para in\u00edcio dos estudos, mas j\u00e1 com investimento divulgado at\u00e9 2040.<\/p>\n<p>\u201cDesde a san\u00e7\u00e3o do marco regulat\u00f3rio, em 2020, o Brasil recebeu o triplo do total investido nas 3 d\u00e9cadas anteriores em apenas 4 anos. As deb\u00eantures e o mercado de capitais s\u00e3o ferramentas oriundas de uma maior seguran\u00e7a jur\u00eddica. O aumento dos investimentos nos novos moldes tamb\u00e9m cria um \u00e2mbito de crescimento tecnol\u00f3gico, especialmente de acr\u00e9scimo de tecnologias embarcadas em equipamentos mecanizados para cumprir com os indicadores exigidos de incremento na efici\u00eancia dos servi\u00e7os de saneamento\u201d, declara Renan Andreguetto, gerente da IFAT Brasil.<\/p>\n<p><strong>Distribui\u00e7\u00e3o<\/strong><\/p>\n<p>O montante dos investimentos n\u00e3o ser\u00e1 distribu\u00eddo de forma homog\u00eanea entre as cinco regi\u00f5es brasileiras no quesito \u00e1gua e esgoto. O Sudeste e o Nordeste concentram mais de 71% dos investimentos, com respectivamente, 41% e 37%. J\u00e1 para regi\u00e3o Sul, cerca de 12% dos investimentos totais est\u00e3o concentrados. As regi\u00f5es com menor concentra\u00e7\u00e3o de investimentos s\u00e3o as regi\u00f5es Centro-Oeste e Norte, com respectivamente, 6% e 4%.<\/p>\n<p>Para Andreguetto, a distribui\u00e7\u00e3o da densidade populacional e governan\u00e7a regulat\u00f3ria de cada regi\u00e3o s\u00e3o os principais fatores que determinam a diferen\u00e7a de distribui\u00e7\u00e3o dos investimentos e projetos previstos. Segundo o levantamento, a regi\u00e3o Norte \u00e9 a regi\u00e3o com menos projetos previstos, com uma fatia de apenas 4%. Apesar de possuir mais residentes que o Centro-Oeste (17,3 milh\u00f5es contra 16,3 milh\u00f5es), ela possui uma taxa de crescimento populacional menor at\u00e9 o horizonte previsto dos projetos (0,75% contra 1,23%).<\/p>\n<p><strong>Regionaliza\u00e7\u00e3o e crescimento<\/strong><\/p>\n<p>As diferentes ferramentas regulat\u00f3rias e de apoio que proporcionaram um bom ambiente para investimentos e seguran\u00e7a jur\u00eddica resultaram em uma economia setorial mais diversificada, com mais instrumentos financeiros dispon\u00edveis e maior apetite por desenvolvimento tecnol\u00f3gico ap\u00f3s quatro anos do Marco Regulat\u00f3rio.<\/p>\n<p>Entre 2015 e 2024, o mercado de deb\u00eantures incentivadas registrou um crescimento de 50%, sendo emitidos mais de R$ 42 milh\u00f5es at\u00e9 a data atual de 2024. Outro excelente indicador \u00e9 o crescimento em consultas p\u00fablicas e contrata\u00e7\u00f5es de projetos de financiamento nos bancos modeladores, que cresceu em m\u00e9dia mais de 30% nos \u00faltimos 4 anos.<\/p>\n<div>\n<div>\n<div class=\"trv-player-container\">\n<div class=\"trv-wrapper\">\n<div id=\"br_video_player_e8e4019058823b81bab71d5d558f2e9dc3c659f9\" class=\"trvd_video_player\">\n<div class=\"media-player\">\n<div class=\"trv-video\">\n<div id=\"truvid_ima_container51201\" class=\"truvid_ima_container\">\n<div>\n<div class=\"conteudo_post\">\n<p>O marco tamb\u00e9m impulsionou a diversifica\u00e7\u00e3o de demanda e oferta do setor. H\u00e1 cerca de 267 empresas privadas que prestam servi\u00e7os p\u00fablicos de distribui\u00e7\u00e3o de \u00e1gua, coleta e tratamento de esgoto, o que representa em m\u00e9dia 5% do total de prestadores de administra\u00e7\u00e3o direta ou autarquia.<\/p>\n<p>A \u00e1gua e o esgoto j\u00e1 s\u00e3o totalmente regionalizados em 23 dos 26 estados (o Distrito Federal n\u00e3o se enquadra nesse quesito). Al\u00e9m do Amap\u00e1, que possui uma modelagem anterior aos decretos regulamentadores, apenas Rio de Janeiro e Minas Gerais ainda est\u00e3o parcialmente regionalizados.<\/p>\n<\/div>\n<div id=\"div-share\">Bahia.ba<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"trv-poster\"><\/div>\n<\/div>\n<div class=\"trv-autoskip-container\">\n<div class=\"trv-autoskip-background\">\n<div class=\"trv-autoskip-line-top\">\n<div><\/div>\n<\/div>\n<div class=\"trv-autoskip-line-right\">\n<div><\/div>\n<\/div>\n<div class=\"trv-autoskip-line-bottom\">\n<div><\/div>\n<\/div>\n<div class=\"trv-autoskip-line-left\">\n<div><\/div>\n<\/div>\n<\/div>\n<div class=\"autoskip-btn autoskip-btn-blue\"><\/div>\n<div class=\"autoskip-btn autoskip-btn-gray\"><\/div>\n<\/div>\n<div><\/div>\n<p><img decoding=\"async\" src=\"https:\/\/ads.stickyadstv.com\/auto-user-sync?_fw_gdpr=0&amp;_fw_gdpr_consent=\" \/><img decoding=\"async\" src=\"https:\/\/ads.stickyadstv.com\/user-matching?id=2545&amp;_fw_gdpr=0&amp;_fw_gdpr_consent=\" \/><\/p>\n<div><\/div>\n<div><\/div>\n<p><img decoding=\"async\" src=\"https:\/\/ads.stickyadstv.com\/auto-user-sync?_fw_gdpr=0&amp;_fw_gdpr_consent=\" \/><img decoding=\"async\" src=\"https:\/\/ads.stickyadstv.com\/user-matching?id=2545&amp;_fw_gdpr=0&amp;_fw_gdpr_consent=\" \/><\/p>\n<div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='Pesquisa mostra que 58,3% dos baianos vivem sem acesso \u00e0 rede de esgoto' data-link='https:\/\/newsinfoco.com.br\/inicio\/37227-2\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Uma pesquisa feita pela IFAT Brasil com a Pezco Economics e a Resolux Company revela os desafios da Bahia no saneamento b\u00e1sico: 58,3% da popula\u00e7\u00e3o do estado n\u00e3o tem acesso \u00e0 rede de esgoto, enquanto 19,4% n\u00e3o s\u00e3o contemplados com rede de \u00e1gua. O levantamento aponta, ainda, outras defici\u00eancias, como a perda de \u00e1gua nas [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":37228,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[19],"tags":[],"class_list":["post-37227","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bahia"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/37227","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/comments?post=37227"}],"version-history":[{"count":3,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/37227\/revisions"}],"predecessor-version":[{"id":37231,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/37227\/revisions\/37231"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media\/37228"}],"wp:attachment":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media?parent=37227"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/categories?post=37227"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/tags?post=37227"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}