{"id":48505,"date":"2025-12-13T21:11:25","date_gmt":"2025-12-14T00:11:25","guid":{"rendered":"https:\/\/newsinfoco.com.br\/inicio\/?p=48505"},"modified":"2025-12-13T21:19:27","modified_gmt":"2025-12-14T00:19:27","slug":"ouvidoria-municipal-de-alagoinhas-encerra-o-ano-com-confraternizacao-e-valorizacao-dos-servidores","status":"publish","type":"post","link":"https:\/\/newsinfoco.com.br\/inicio\/ouvidoria-municipal-de-alagoinhas-encerra-o-ano-com-confraternizacao-e-valorizacao-dos-servidores\/","title":{"rendered":"Ouvidoria Municipal de Alagoinhas encerra o ano com confraterniza\u00e7\u00e3o e valoriza\u00e7\u00e3o dos servidores"},"content":{"rendered":"<p>A Ouvidoria Municipal da Prefeitura de Alagoinhas realizou, nesta semana, sua confraterniza\u00e7\u00e3o de final de ano, marcando o encerramento das atividades de 2025 com um momento de integra\u00e7\u00e3o, reconhecimento e valoriza\u00e7\u00e3o do trabalho desenvolvido ao longo do per\u00edodo<\/p>\n<p>O encontro reuniu servidores e colaboradores da Ouvidoria em um ambiente de celebra\u00e7\u00e3o pelas conquistas alcan\u00e7adas, pelo fortalecimento dos la\u00e7os institucionais e pelo compromisso coletivo com um servi\u00e7o p\u00fablico pautado pela \u00e9tica, seriedade, humaniza\u00e7\u00e3o e excel\u00eancia no atendimento \u00e0 popula\u00e7\u00e3o.<\/p><div class=\"newsi-conteudo_19\" id=\"newsi-1768056165\"><a href=\"https:\/\/www.instagram.com\/prefeituraalagoinhas?igsh=YzgzdDJ1bWR3aWI4\" aria-label=\"SAVE_20251006_221555\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg\" alt=\"\"  srcset=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg 1140w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-300x52.jpg 300w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1024x177.jpg 1024w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-768x133.jpg 768w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-600x104.jpg 600w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-696x120.jpg 696w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1068x185.jpg 1068w\" sizes=\"(max-width: 1140px) 100vw, 1140px\" width=\"1140\" height=\"197\"   \/><\/a><\/div>\n<p>A confraterniza\u00e7\u00e3o contou com a presen\u00e7a do prefeito Gustavo Carmo, que prestigiou o evento e reafirmou o reconhecimento da gest\u00e3o municipal ao trabalho desempenhado pela Ouvidoria. Na ocasi\u00e3o, o gestor destacou a import\u00e2ncia do \u00f3rg\u00e3o para o fortalecimento da administra\u00e7\u00e3o p\u00fablica, assegurando apoio institucional e a garantia da imparcialidade necess\u00e1ria para o pleno funcionamento do setor.<\/p>\n<p>Durante o evento, foi ressaltado o empenho de cada servidor e servidora, cuja dedica\u00e7\u00e3o e esp\u00edrito de parceria contribuem diariamente para a constru\u00e7\u00e3o de uma Ouvidoria atuante, transparente e comprometida com os cidad\u00e3os de Alagoinhas.<\/p>\n<div class=\"texto\">\n<p data-start=\"1195\" data-end=\"1412\" data-is-last-node=\"\" data-is-only-node=\"\">Ao final, a equipe desejou votos de boas festas, com mensagens de paz, sa\u00fade e renova\u00e7\u00e3o das energias, refor\u00e7ando a expectativa de um novo ano marcado por ainda mais realiza\u00e7\u00f5es e avan\u00e7os no servi\u00e7o p\u00fablico municipal.<\/p>\n<\/div>\n<div class=\"pgwSlideshow wide\">\n<div class=\"ps-current\">Fonte: Se Liga Alagoinhas<\/div>\n<\/div>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='Ouvidoria Municipal de Alagoinhas encerra o ano com confraterniza\u00e7\u00e3o e valoriza\u00e7\u00e3o dos servidores' data-link='https:\/\/newsinfoco.com.br\/inicio\/ouvidoria-municipal-de-alagoinhas-encerra-o-ano-com-confraternizacao-e-valorizacao-dos-servidores\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>A Ouvidoria Municipal da Prefeitura de Alagoinhas realizou, nesta semana, sua confraterniza\u00e7\u00e3o de final de ano, marcando o encerramento das atividades de 2025 com um momento de integra\u00e7\u00e3o, reconhecimento e valoriza\u00e7\u00e3o do trabalho desenvolvido ao longo do per\u00edodo O encontro reuniu servidores e colaboradores da Ouvidoria em um ambiente de celebra\u00e7\u00e3o pelas conquistas alcan\u00e7adas, pelo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":48506,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[38,30,167,1],"tags":[],"class_list":["post-48505","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alagoinhas-e-regiao","category-destaque","category-exclusivas","category-sem-categoria"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/48505","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/comments?post=48505"}],"version-history":[{"count":2,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/48505\/revisions"}],"predecessor-version":[{"id":48509,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/48505\/revisions\/48509"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media\/48506"}],"wp:attachment":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media?parent=48505"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/categories?post=48505"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/tags?post=48505"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}