{"id":50036,"date":"2026-03-26T10:35:26","date_gmt":"2026-03-26T13:35:26","guid":{"rendered":"https:\/\/newsinfoco.com.br\/inicio\/?p=50036"},"modified":"2026-03-26T10:35:26","modified_gmt":"2026-03-26T13:35:26","slug":"prefeitura-de-alagoinhas-faz-triagem-de-200-pessoas-para-cirurgias-de-catarata-e-pterigio","status":"publish","type":"post","link":"https:\/\/newsinfoco.com.br\/inicio\/prefeitura-de-alagoinhas-faz-triagem-de-200-pessoas-para-cirurgias-de-catarata-e-pterigio\/","title":{"rendered":"Prefeitura de Alagoinhas faz triagem de 200 pessoas para cirurgias de catarata e pter\u00edgio"},"content":{"rendered":"<p>Entre os dias 24 e 25, o Centro de Cirurgias Eletivas Jud\u00e9lio Carmo realizou triagem para cirurgias de catarata, pter\u00edgio e limpeza da lente (Yag laser). A a\u00e7\u00e3o, que atendeu a 200 pacientes e foi promovida pela Secretaria Municipal de Sa\u00fade (Sesau) em parceria com o Instituto de Oftalmologia de Feira de Santana (IOFS), contou com consultas e marca\u00e7\u00e3o de exames laboratoriais e eletrocardiograma pr\u00e9-operat\u00f3rios. As cirurgias est\u00e3o previstas para os dias 7 e 8 de abril<\/p>\n<p>A coordenadora do Centro de Cirurgias Eletivas, Marluce Lima, destaca que a iniciativa integra os esfor\u00e7os da Prefeitura para reduzir filas de espera por atendimento na rede p\u00fablica. \u201cAo controlar uma demanda reprimida, a gest\u00e3o municipal agiliza as respostas \u00e0 popula\u00e7\u00e3o, contribuindo para o bem-estar e qualidade de vida dos pacientes e at\u00e9 mesmo de suas fam\u00edlias\u201d, observa.<\/p><div class=\"newsi-conteudo_19\" id=\"newsi-1198043456\"><a href=\"https:\/\/www.instagram.com\/prefeituraalagoinhas?igsh=YzgzdDJ1bWR3aWI4\" aria-label=\"SAVE_20251006_221555\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg\" alt=\"\"  srcset=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg 1140w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-300x52.jpg 300w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1024x177.jpg 1024w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-768x133.jpg 768w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-600x104.jpg 600w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-696x120.jpg 696w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1068x185.jpg 1068w\" sizes=\"(max-width: 1140px) 100vw, 1140px\" width=\"1140\" height=\"197\"   \/><\/a><\/div>\n<p>De acordo com Marluce, a parceria com o IOFS \u00e9 muito importante, por se tratar de um centro de refer\u00eancia em tratamentos especializados e exames avan\u00e7ados. J\u00e1 a coordenadora da IOFS, Amanda Teixeira de Freitas Oliveira, destaca que a participa\u00e7\u00e3o do instituto na iniciativa da prefeitura \u201crefor\u00e7a, inclusive, seu papel social de oferecer ao maior n\u00famero poss\u00edvel de pessoas o acesso a procedimentos oftalmol\u00f3gicos\u201d.<\/p>\n<p>Uma das pessoas atendidas foi a enfermeira Rita Pereira, 41 anos, que usa \u00f3culos desde os 9 por conta de astigmatismo e hipermetropia. Recentemente, ela descobriu que tamb\u00e9m tem catarata no olho esquerdo e decidiu buscar tratamento. \u201cCom esta oportunidade, minha expectativa \u00e9 diminuir o grau dos \u00f3culos e voltar a enxergar normalmente, porque j\u00e1 n\u00e3o consigo ler nomes pequenos em embalagens\u201d, diz.<\/p>\n<p>Outra paciente, a monitora infantil Jeane de Jesus Bittencourt, 30 anos, relata que tem inflama\u00e7\u00e3o e grandes inc\u00f4modos no olho direito desde dezembro, com sensibilidade \u00e0 claridade. Ela buscou o mutir\u00e3o para avaliar a possibilidade de cirurgia e ficou satisfeita com o atendimento. \u201cMelhorar a vista \u00e9 essencial para n\u00e3o depender dos outros e retomar meu trabalho e qualidade de vida\u201d, afirma.<\/p>\n<p><a class=\"group1 cboxElement\" href=\"https:\/\/www.alagoinhas.ba.gov.br\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-25-at-15.10.21-2.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-88276\" src=\"https:\/\/www.alagoinhas.ba.gov.br\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-25-at-15.10.21-2.jpeg\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\" srcset=\"https:\/\/www.alagoinhas.ba.gov.br\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-25-at-15.10.21-2.jpeg 1600w, https:\/\/www.alagoinhas.ba.gov.br\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-25-at-15.10.21-2-300x225.jpeg 300w, https:\/\/www.alagoinhas.ba.gov.br\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-25-at-15.10.21-2-768x576.jpeg 768w, https:\/\/www.alagoinhas.ba.gov.br\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-25-at-15.10.21-2-1024x768.jpeg 1024w, https:\/\/www.alagoinhas.ba.gov.br\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-25-at-15.10.21-2-24x18.jpeg 24w\" alt=\"\" width=\"1600\" height=\"1200\" \/><\/a><\/p>\n<p><a class=\"group1 cboxElement\" href=\"https:\/\/www.alagoinhas.ba.gov.br\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-25-at-15.10.20.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-88273\" src=\"https:\/\/www.alagoinhas.ba.gov.br\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-25-at-15.10.20.jpeg\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\" srcset=\"https:\/\/www.alagoinhas.ba.gov.br\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-25-at-15.10.20.jpeg 1600w, https:\/\/www.alagoinhas.ba.gov.br\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-25-at-15.10.20-300x225.jpeg 300w, https:\/\/www.alagoinhas.ba.gov.br\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-25-at-15.10.20-768x576.jpeg 768w, https:\/\/www.alagoinhas.ba.gov.br\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-25-at-15.10.20-1024x768.jpeg 1024w, https:\/\/www.alagoinhas.ba.gov.br\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-25-at-15.10.20-24x18.jpeg 24w\" alt=\"\" width=\"1600\" height=\"1200\" \/><\/a><\/p>\n<p><strong>Fotos: Secom\/Alagoinhas<\/strong><\/p>\n<div align=\"right\"><\/div>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='Prefeitura de Alagoinhas faz triagem de 200 pessoas para cirurgias de catarata e pter\u00edgio' data-link='https:\/\/newsinfoco.com.br\/inicio\/prefeitura-de-alagoinhas-faz-triagem-de-200-pessoas-para-cirurgias-de-catarata-e-pterigio\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Entre os dias 24 e 25, o Centro de Cirurgias Eletivas Jud\u00e9lio Carmo realizou triagem para cirurgias de catarata, pter\u00edgio e limpeza da lente (Yag laser). A a\u00e7\u00e3o, que atendeu a 200 pacientes e foi promovida pela Secretaria Municipal de Sa\u00fade (Sesau) em parceria com o Instituto de Oftalmologia de Feira de Santana (IOFS), contou [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":50037,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[38,30,167],"tags":[],"class_list":["post-50036","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alagoinhas-e-regiao","category-destaque","category-exclusivas"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/50036","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/comments?post=50036"}],"version-history":[{"count":1,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/50036\/revisions"}],"predecessor-version":[{"id":50038,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/50036\/revisions\/50038"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media\/50037"}],"wp:attachment":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media?parent=50036"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/categories?post=50036"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/tags?post=50036"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}