{"id":50057,"date":"2026-03-28T12:11:46","date_gmt":"2026-03-28T15:11:46","guid":{"rendered":"https:\/\/newsinfoco.com.br\/inicio\/?p=50057"},"modified":"2026-03-28T12:11:46","modified_gmt":"2026-03-28T15:11:46","slug":"prefeito-gustavo-carmo-institui-comite-gestor-fiscal-em-alagoinhas-2","status":"publish","type":"post","link":"https:\/\/newsinfoco.com.br\/inicio\/prefeito-gustavo-carmo-institui-comite-gestor-fiscal-em-alagoinhas-2\/","title":{"rendered":"Prefeito Gustavo Carmo institui Comit\u00ea Gestor Fiscal em Alagoinhas"},"content":{"rendered":"<p>O prefeito Gustavo Carmo assinou, nesta sexta-feira, 27, o Decreto n\u00ba 6.605, que institui o Comit\u00ea Gestor Fiscal de Alagoinhas. Coordenado pela Secretaria da Fazenda, o comit\u00ea ter\u00e1 a responsabilidade de executar o Plano de Contingenciamento de Gastos do munic\u00edpio. O objetivo \u00e9 priorizar a\u00e7\u00f5es emergenciais ap\u00f3s os estragos das fortes chuvas e manter as a\u00e7\u00f5es do plano de desenvolvimento da cidade, com equil\u00edbrio or\u00e7ament\u00e1rio e manuten\u00e7\u00e3o de obriga\u00e7\u00f5es essenciais, como folha de pagamento, investimentos em sa\u00fade, educa\u00e7\u00e3o, assist\u00eancia social e infraestrutura.<\/p>\n<p>Alinhado \u00e0 Lei de Responsabilidade Fiscal e ao estado de emerg\u00eancia (Decreto n\u00ba 6.577\/2026), o comit\u00ea revisar\u00e1 despesas, suspender\u00e1 novos investimentos n\u00e3o urgentes, exceto obriga\u00e7\u00f5es constitucionais e obras essenciais, e avaliar\u00e1 contratos vigentes, sem interromper servi\u00e7os b\u00e1sicos.<\/p><div class=\"newsi-conteudo_19\" id=\"newsi-3043813975\"><a href=\"https:\/\/www.instagram.com\/prefeituraalagoinhas?igsh=YzgzdDJ1bWR3aWI4\" aria-label=\"SAVE_20251006_221555\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg\" alt=\"\"  srcset=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg 1140w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-300x52.jpg 300w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1024x177.jpg 1024w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-768x133.jpg 768w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-600x104.jpg 600w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-696x120.jpg 696w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1068x185.jpg 1068w\" sizes=\"(max-width: 1140px) 100vw, 1140px\" width=\"1140\" height=\"197\"   \/><\/a><\/div>\n<p>\u201cSeguiremos acolhendo as fam\u00edlias afetadas pelas chuvas, vamos reerguer a nossa cidade e faremos tudo isso sem comprometer o nosso futuro, garantindo que cada centavo seja aplicado de forma respons\u00e1vel e transparente\u201d, destaca o prefeito Gustavo.<\/p>\n<p>O plano de desenvolvimento municipal prev\u00ea obras como constru\u00e7\u00e3o e reforma de creches, unidades de sa\u00fade e pavimenta\u00e7\u00e3o de vias. Muitas dessas interven\u00e7\u00f5es t\u00eam apoio financeiro estadual e federal, mas demandam recursos locais.<\/p>\n<p>\u201cNeste contexto, fomos surpreendidos por chuvas intensas, como h\u00e1 muito tempo n\u00e3o v\u00edamos. Isso gerou despesas imprevistas. O trabalho do comit\u00ea nos permitir\u00e1 priorizar o essencial: cuidar das fam\u00edlias afetadas, manter servi\u00e7os b\u00e1sicos e avan\u00e7ar a cidade apesar das dificuldades\u201d, comenta Carmo.<\/p>\n<p>O decreto tem validade de 90 dias. \u201cEste ajuste \u00e9 necess\u00e1rio para atravessarmos o momento com seguran\u00e7a. \u00c9 o que qualquer pessoa faria em casa e o que os cidad\u00e3os esperam de um prefeito: prioridade ao essencial, prud\u00eancia e responsabilidade. Conto com a compreens\u00e3o e o apoio de todos para reerguer Alagoinhas sem comprometer o nosso futuro\u201d, enfatiza Gustavo Carmo.<\/p>\n<p>&nbsp;<\/p>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='Prefeito Gustavo Carmo institui Comit\u00ea Gestor Fiscal em Alagoinhas' data-link='https:\/\/newsinfoco.com.br\/inicio\/prefeito-gustavo-carmo-institui-comite-gestor-fiscal-em-alagoinhas-2\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>O prefeito Gustavo Carmo assinou, nesta sexta-feira, 27, o Decreto n\u00ba 6.605, que institui o Comit\u00ea Gestor Fiscal de Alagoinhas. Coordenado pela Secretaria da Fazenda, o comit\u00ea ter\u00e1 a responsabilidade de executar o Plano de Contingenciamento de Gastos do munic\u00edpio. O objetivo \u00e9 priorizar a\u00e7\u00f5es emergenciais ap\u00f3s os estragos das fortes chuvas e manter as [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":50054,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[38,30,167],"tags":[],"class_list":["post-50057","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alagoinhas-e-regiao","category-destaque","category-exclusivas"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/50057","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/comments?post=50057"}],"version-history":[{"count":1,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/50057\/revisions"}],"predecessor-version":[{"id":50058,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/50057\/revisions\/50058"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media\/50054"}],"wp:attachment":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media?parent=50057"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/categories?post=50057"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/tags?post=50057"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}