{"id":50189,"date":"2026-04-08T15:48:49","date_gmt":"2026-04-08T18:48:49","guid":{"rendered":"https:\/\/newsinfoco.com.br\/inicio\/?p=50189"},"modified":"2026-04-08T15:48:49","modified_gmt":"2026-04-08T18:48:49","slug":"camara-municipal-une-se-contra-desinformacao-e-debate-etica-na-vida-publica","status":"publish","type":"post","link":"https:\/\/newsinfoco.com.br\/inicio\/camara-municipal-une-se-contra-desinformacao-e-debate-etica-na-vida-publica\/","title":{"rendered":"C\u00e2mara Municipal une-se contra desinforma\u00e7\u00e3o e debate \u00e9tica na vida p\u00fablica"},"content":{"rendered":"<p>Debate sobre a verdade, desinforma\u00e7\u00e3o e \u00e9tica na vida p\u00fablica movimentou o grande expediente na sess\u00e3o desta ter\u00e7a-feira (7). Vereadores de oposi\u00e7\u00e3o e situa\u00e7\u00e3o uniram-se para repudiar mat\u00e9ria divulgada pelo Sindicato dos Trabalhadores em \u00c1gua, Esgoto e Meio Ambiente (SINDAE) que acusa parlamentares de oposi\u00e7\u00e3o de articularem a privatiza\u00e7\u00e3o do Servi\u00e7o Aut\u00f4nomo de \u00c1gua e Esgoto (SAAE).<\/p>\n<p>O vereador Luciano Almeida manifestou surpresa e indigna\u00e7\u00e3o com a mat\u00e9ria do sindicato. Para ele, a tentativa de vincular a defesa de tarifas mais baixas \u00e0 privatiza\u00e7\u00e3o \u00e9 uma \u201cmanobra mentirosa\u201d para encobrir falhas administrativas.<\/p><div class=\"newsi-conteudo_19\" id=\"newsi-665358224\"><a href=\"https:\/\/www.instagram.com\/prefeituraalagoinhas?igsh=YzgzdDJ1bWR3aWI4\" aria-label=\"SAVE_20251006_221555\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg\" alt=\"\"  srcset=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg 1140w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-300x52.jpg 300w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1024x177.jpg 1024w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-768x133.jpg 768w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-600x104.jpg 600w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-696x120.jpg 696w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1068x185.jpg 1068w\" sizes=\"(max-width: 1140px) 100vw, 1140px\" width=\"1140\" height=\"197\"   \/><\/a><\/div>\n<p>\u201cDefender a popula\u00e7\u00e3o e cobrar taxas justas n\u00e3o \u00e9 querer privatizar. O que vemos \u00e9 um sucateamento do SAAE, com comunidades sendo abastecidas por carro-pipa. O sindicato, em vez de fiscalizar a gest\u00e3o e o aumento da tarifa de esgoto de 40% para 80%, prefere criar\u00a0<em>fake news<\/em>\u00a0contra quem trabalha. Desafio o sindicato e o SAAE a abrirem a \u2018caixa preta\u2019 da autarquia nesta Casa\u201d, argumentou.<\/p>\n<div class=\"wp-block-image\"><\/div>\n<p>A vereadora Luma Menezes\u00a0 classificou a mat\u00e9ria como \u201cbizarra e inacredit\u00e1vel\u201d. Ela destacou que a pr\u00f3pria Lei Org\u00e2nica do Munic\u00edpio impede que o Parlamento inicie processos de privatiza\u00e7\u00e3o, tarefa que caberia exclusivamente ao Executivo ap\u00f3s consulta popular.<\/p>\n<p>\u201cA quem interessa criar essa mentira? \u00c9 para que a gente se cale sobre a falta de \u00e1gua e os alagamentos nas periferias? N\u00e3o iremos parar. Nossa atua\u00e7\u00e3o \u00e9 por solu\u00e7\u00f5es de baixo custo para a popula\u00e7\u00e3o de baixa renda. Pa\u00edses que privatizaram o saneamento est\u00e3o voltando atr\u00e1s pela desigualdade gerada. Eu nunca defendi e nunca defenderei a privatiza\u00e7\u00e3o da \u00e1gua\u201d, afirmou.<\/p>\n<div class=\"wp-block-image\"><\/div>\n<p>Em contrapartida, o l\u00edder do governo, Thor de Ninha, utilizou seu tempo para responder \u00e0s acusa\u00e7\u00f5es de que teria articulado o esvaziamento da audi\u00eancia p\u00fablica da oposi\u00e7\u00e3o. Em um discurso carregado de refer\u00eancias \u00e0 sua hist\u00f3ria pessoal, Thor negou qualquer ato de deslealdade.<\/p>\n<p>\u201cFui julgado e sentenciado em pra\u00e7a p\u00fablica por uma mentira. Jamais articulei contra a presen\u00e7a do SAAE ou de qualquer servidor nesta Casa. Minha hist\u00f3ria de vida, vinda de uma fam\u00edlia de oito irm\u00e3os que passaram fome, n\u00e3o me permite ser desonesto. Posso discordar da oposi\u00e7\u00e3o no campo das ideias e combater o carlismo e a extrema direita, mas jamais atacarei a honra ou a capacidade de um colega pelas costas\u201d, defendeu Thor.<\/p>\n<div class=\"wp-block-image\"><\/div>\n<p>O l\u00edder governista tamb\u00e9m aproveitou para cobrar que a oposi\u00e7\u00e3o retire postagens das redes sociais que o colocam como \u201cvil\u00e3o\u201d de uma articula\u00e7\u00e3o inexistente. \u201cA desinforma\u00e7\u00e3o mata. Se eu tiver uma \u00fanica fala desrespeitando a vereadora Luma, eu fa\u00e7o quest\u00e3o de compartilhar e pedir desculpas. Fora isso, exijo respeito\u201d, concluiu.<\/p>\n<p>A vereadora Juci Cardoso afirmou que a falta de argumentos muitas vezes leva ao ataque pessoal. \u201cReconhecer problemas no abastecimento n\u00e3o \u00e9 ser contra o governo, \u00e9 viver a realidade. Quando falta preparo e \u00e9tica, resta a mentira. Precisamos elevar o debate e parar de tratar a cidade como um cl\u00e1ssico \u2018Ba-Vi&#8217;\u201d, ponderou.<\/p>\n<div class=\"wp-block-image\"><\/div>\n<p>O vereador Jorge da Farinha tamb\u00e9m se solidarizou com os colegas citados pelo sindicato, afirmando que a acusa\u00e7\u00e3o atinge todo o colegiado. \u201cEstou no sexto mandato e nunca vi esta Casa tocar em privatiza\u00e7\u00e3o. Defendemos o SAAE, mas um SAAE que funcione e que atenda os pedidos de extens\u00e3o de rede que hoje est\u00e3o travados\u201d, disse Jorge.<\/p>\n<div class=\"wp-block-image\"><\/div>\n<p>Ao encerrar a sess\u00e3o, o presidente da Casa<strong>,\u00a0<\/strong>Cleto da Banana, acolheu o pedido un\u00e2nime dos parlamentares e determinou que a assessoria de comunica\u00e7\u00e3o emita uma nota oficial de rep\u00fadio contra a desinforma\u00e7\u00e3o veiculada pelo sindicato.<\/p>\n<p>\u201cEsta Casa n\u00e3o pode aceitar mentiras que firam a integridade de seus membros. Emitiremos uma nota restabelecendo a verdade e reafirmando o compromisso deste Parlamento com o servi\u00e7o p\u00fablico de qualidade e a transpar\u00eancia\u201d, declarou.<\/p>\n<p><strong>Ascom \u2013 C\u00e2mara Municipal de Alagoinhas<\/strong><\/p>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='C\u00e2mara Municipal une-se contra desinforma\u00e7\u00e3o e debate \u00e9tica na vida p\u00fablica' data-link='https:\/\/newsinfoco.com.br\/inicio\/camara-municipal-une-se-contra-desinformacao-e-debate-etica-na-vida-publica\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Debate sobre a verdade, desinforma\u00e7\u00e3o e \u00e9tica na vida p\u00fablica movimentou o grande expediente na sess\u00e3o desta ter\u00e7a-feira (7). Vereadores de oposi\u00e7\u00e3o e situa\u00e7\u00e3o uniram-se para repudiar mat\u00e9ria divulgada pelo Sindicato dos Trabalhadores em \u00c1gua, Esgoto e Meio Ambiente (SINDAE) que acusa parlamentares de oposi\u00e7\u00e3o de articularem a privatiza\u00e7\u00e3o do Servi\u00e7o Aut\u00f4nomo de \u00c1gua e [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":50190,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[19],"tags":[],"class_list":["post-50189","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bahia"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/50189","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/comments?post=50189"}],"version-history":[{"count":1,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/50189\/revisions"}],"predecessor-version":[{"id":50191,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/50189\/revisions\/50191"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media\/50190"}],"wp:attachment":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media?parent=50189"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/categories?post=50189"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/tags?post=50189"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}