{"id":50199,"date":"2026-04-08T16:03:06","date_gmt":"2026-04-08T19:03:06","guid":{"rendered":"https:\/\/newsinfoco.com.br\/inicio\/?p=50199"},"modified":"2026-04-08T16:03:06","modified_gmt":"2026-04-08T19:03:06","slug":"alagoinhas-realiza-mutirao-e-amplia-acesso-a-cirurgias-oftalmologicas","status":"publish","type":"post","link":"https:\/\/newsinfoco.com.br\/inicio\/alagoinhas-realiza-mutirao-e-amplia-acesso-a-cirurgias-oftalmologicas\/","title":{"rendered":"Alagoinhas realiza mutir\u00e3o e amplia acesso a cirurgias oftalmol\u00f3gicas"},"content":{"rendered":"<p>O Centro de Cirurgias Eletivas Jud\u00e9lio de Souza Carmo est\u00e1 realizando, entre os dias 7 e 8 de abril, mais um mutir\u00e3o oftalmol\u00f3gico com foco na amplia\u00e7\u00e3o do acesso a procedimentos especializados. A iniciativa contempla cirurgias de catarata, limpeza de lente e tratamento de pter\u00edgio.<\/p>\n<p>Totalizando 140 procedimentos, a mobiliza\u00e7\u00e3o da Secretaria Municipal de Sa\u00fade (Sesau) busca reduzir a fila de espera por cirurgias nessa especialidade, garantindo maior agilidade no atendimento e contribuindo para a melhoria da qualidade de vida dos pacientes atendidos.<\/p><div class=\"newsi-conteudo_19\" id=\"newsi-507238883\"><a href=\"https:\/\/www.instagram.com\/prefeituraalagoinhas?igsh=YzgzdDJ1bWR3aWI4\" aria-label=\"SAVE_20251006_221555\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg\" alt=\"\"  srcset=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg 1140w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-300x52.jpg 300w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1024x177.jpg 1024w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-768x133.jpg 768w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-600x104.jpg 600w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-696x120.jpg 696w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1068x185.jpg 1068w\" sizes=\"(max-width: 1140px) 100vw, 1140px\" width=\"1140\" height=\"197\"   \/><\/a><\/div>\n<p>Realizada em parceria com o Instituto de Olhos de Feira de Santana (IOFS), a iniciativa tamb\u00e9m tem como objetivo diminuir a fila de espera do Sistema \u00danico de Sa\u00fade (SUS) no munic\u00edpio. \u201c\u00c9 \u00f3timo ouvir e sentir do paciente que estamos realizando um trabalho com cuidado e que atingimos nosso objetivo, porque eles est\u00e3o saindo satisfeitos e com a vis\u00e3o restabelecida. Isso nos traz uma sensa\u00e7\u00e3o de dever cumprido e de grande satisfa\u00e7\u00e3o\u201d, comemora a coordenadora da a\u00e7\u00e3o, B\u00e1rbara de Jesus Santos.<\/p>\n<p>Maria de Lourdes de Reis dos Santos, 60 anos, que passou por cirurgia de catarata, falou sobre o seu processo. \u201cEu fiz a cirurgia no olho esquerdo e j\u00e1 tinha feito anteriormente no direito. Na minha revis\u00e3o, o m\u00e9dico disse que estou evoluindo bem e espero logo estar com minha vis\u00e3o 100% recuperada para que eu possa levar a vida com mais tranquilidade e independ\u00eancia\u201d, disse.<\/p>\n<p>De acordo com o secret\u00e1rio de Sa\u00fade, Luciano S\u00e9rgio, o mutir\u00e3o fortalece a sa\u00fade p\u00fablica no munic\u00edpio. \u201cSabemos o quanto a vis\u00e3o \u00e9 essencial para a qualidade de vida das pessoas. Muitas vezes, problemas que poderiam ser resolvidos com um procedimento relativamente simples acabam se tornando obst\u00e1culos no dia a dia, dificultando o trabalho, os estudos e at\u00e9 mesmo atividades b\u00e1sicas. Estamos priorizando pacientes que aguardavam h\u00e1 bastante tempo e garantindo um atendimento humanizado, seguro e de qualidade\u201d, destacou.<\/p>\n<p>Segundo informa\u00e7\u00f5es das equipes do Centro de Eletivas, as pr\u00f3ximas cirurgias oftalmol\u00f3gicas est\u00e3o marcadas para os dias 18 e 19 de maio.<\/p>\n<p>&nbsp;<\/p>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='Alagoinhas realiza mutir\u00e3o e amplia acesso a cirurgias oftalmol\u00f3gicas' data-link='https:\/\/newsinfoco.com.br\/inicio\/alagoinhas-realiza-mutirao-e-amplia-acesso-a-cirurgias-oftalmologicas\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>O Centro de Cirurgias Eletivas Jud\u00e9lio de Souza Carmo est\u00e1 realizando, entre os dias 7 e 8 de abril, mais um mutir\u00e3o oftalmol\u00f3gico com foco na amplia\u00e7\u00e3o do acesso a procedimentos especializados. A iniciativa contempla cirurgias de catarata, limpeza de lente e tratamento de pter\u00edgio. Totalizando 140 procedimentos, a mobiliza\u00e7\u00e3o da Secretaria Municipal de Sa\u00fade [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":50200,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[38,167],"tags":[],"class_list":["post-50199","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alagoinhas-e-regiao","category-exclusivas"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/50199","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/comments?post=50199"}],"version-history":[{"count":1,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/50199\/revisions"}],"predecessor-version":[{"id":50201,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/50199\/revisions\/50201"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media\/50200"}],"wp:attachment":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media?parent=50199"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/categories?post=50199"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/tags?post=50199"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}