{"id":50206,"date":"2026-04-08T16:25:56","date_gmt":"2026-04-08T19:25:56","guid":{"rendered":"https:\/\/newsinfoco.com.br\/inicio\/?p=50206"},"modified":"2026-04-08T16:25:56","modified_gmt":"2026-04-08T19:25:56","slug":"vereador-luciano-almeida-critica-demora-na-homologacao-da-licitacao-da-obra-do-viaduto-da-rua-do-catu","status":"publish","type":"post","link":"https:\/\/newsinfoco.com.br\/inicio\/vereador-luciano-almeida-critica-demora-na-homologacao-da-licitacao-da-obra-do-viaduto-da-rua-do-catu\/","title":{"rendered":"Vereador Luciano Almeida critica demora na homologa\u00e7\u00e3o da licita\u00e7\u00e3o da obra do viaduto da rua do Catu"},"content":{"rendered":"<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-166fa74c\" data-id=\"166fa74c\" data-element_type=\"column\">\n<div class=\"elementor-widget-wrap elementor-element-populated\">\n<div class=\"elementor-element elementor-element-8956c80 elementor-widget elementor-widget-theme-post-content\" data-id=\"8956c80\" data-element_type=\"widget\" data-widget_type=\"theme-post-content.default\">\n<div class=\"elementor-widget-container\">\n<p>Na sess\u00e3o realizada nesta ter\u00e7a-feira (7), o vereador Luciano Almeida comentou sobre o andamento da licita\u00e7\u00e3o para a reconstru\u00e7\u00e3o do viaduto em Alagoinhas e afirmou que o processo ocorreu no dia 31 de mar\u00e7o deste ano, na sede da Companhia de Desenvolvimento Urbano do Estado da Bahia (CONDER). De acordo com o parlamentar, a empresa classificada foi a Trilho Engenharia Ltda., com proposta de R$ 7,8 milh\u00f5es, mas a licita\u00e7\u00e3o ainda n\u00e3o foi homologada devido \u00e0 interposi\u00e7\u00e3o de recursos e tr\u00e2mites administrativos.<\/p>\n<p>O vereador explicou que, ap\u00f3s a homologa\u00e7\u00e3o, a empresa dever\u00e1 ser contratada inicialmente para a elabora\u00e7\u00e3o do projeto de engenharia e do projeto executivo da obra, etapa que antecede o in\u00edcio da execu\u00e7\u00e3o. Segundo ele, o prazo previsto para essa fase \u00e9 de tr\u00eas meses, seguidos por cerca de oito meses para a realiza\u00e7\u00e3o dos servi\u00e7os.<\/p><div class=\"newsi-conteudo_19\" id=\"newsi-2930635289\"><a href=\"https:\/\/www.instagram.com\/prefeituraalagoinhas?igsh=YzgzdDJ1bWR3aWI4\" aria-label=\"SAVE_20251006_221555\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg\" alt=\"\"  srcset=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg 1140w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-300x52.jpg 300w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1024x177.jpg 1024w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-768x133.jpg 768w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-600x104.jpg 600w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-696x120.jpg 696w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1068x185.jpg 1068w\" sizes=\"(max-width: 1140px) 100vw, 1140px\" width=\"1140\" height=\"197\"   \/><\/a><\/div>\n<p>\u201cEm um primeiro momento, a empresa ser\u00e1 contratada para elaborar o projeto de engenharia, realizar os estudos t\u00e9cnicos necess\u00e1rios e desenvolver o projeto executivo da obra. O prazo previsto para essa etapa \u00e9 de tr\u00eas meses\u201d, afirmou.<\/p>\n<p>Luciano Almeida levantou questionamentos sobre a viabilidade da execu\u00e7\u00e3o da obra dentro do atual cen\u00e1rio pol\u00edtico e administrativo, especialmente por coincidir com o per\u00edodo eleitoral. Ele citou ainda dados sobre obras paralisadas no estado, apontando dificuldades enfrentadas por empresas em contratos p\u00fablicos.<\/p>\n<p>Durante o pronunciamento, o vereador destacou os impactos causados pela situa\u00e7\u00e3o do viaduto, que, segundo ele, permanece sem solu\u00e7\u00e3o h\u00e1 cerca de dois anos. O local, situado na regi\u00e3o da Rua do Catu e do bairro Teres\u00f3polis, \u00e9 considerado um dos principais acessos ao munic\u00edpio, concentrando fluxo intenso de ve\u00edculos, sobretudo nos hor\u00e1rios de pico.<\/p>\n<p>\u201cNos hor\u00e1rios de maior movimento \u2013 pela manh\u00e3, ao meio-dia e no per\u00edodo da noite -, o tr\u00e2nsito no local se torna ca\u00f3tico e desorganizado, gerando grandes transtornos \u00e0 popula\u00e7\u00e3o\u201d, declarou.<\/p>\n<p>O parlamentar tamb\u00e9m ressaltou preju\u00edzos ao com\u00e9rcio local e aos moradores da regi\u00e3o, al\u00e9m de mencionar que o trecho \u00e9 utilizado por condutores vindos de munic\u00edpios vizinhos como Aramari, \u00c1gua Fria, Irar\u00e1 e Santan\u00f3polis, o que amplia os impactos na mobilidade urbana.<\/p>\n<p>Ao final, o vereador Luciano Almeida criticou a condu\u00e7\u00e3o do processo por parte do Governo do Estado e afirmou que a demora na efetiva\u00e7\u00e3o da obra tem gerado transtornos cont\u00ednuos \u00e0 popula\u00e7\u00e3o. \u201cObserva-se uma inoper\u00e2ncia e um desrespeito por parte do Governo do Estado diante dessa situa\u00e7\u00e3o\u201d, concluiu.<\/p>\n<p><strong>Ascom \u2013 C\u00e2mara Municipal de Alagoinhas<\/strong><\/p>\n<p><strong>Fotos \u2013 Jh\u00f4 Paz<\/strong><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-263f143b\" data-id=\"263f143b\" data-element_type=\"column\">\n<div class=\"elementor-widget-wrap elementor-element-populated\">\n<div class=\"elementor-element elementor-element-19118fd7 elementor-widget elementor-widget-heading\" data-id=\"19118fd7\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n<div class=\"elementor-widget-container\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='Vereador Luciano Almeida critica demora na homologa\u00e7\u00e3o da licita\u00e7\u00e3o da obra do viaduto da rua do Catu' data-link='https:\/\/newsinfoco.com.br\/inicio\/vereador-luciano-almeida-critica-demora-na-homologacao-da-licitacao-da-obra-do-viaduto-da-rua-do-catu\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Na sess\u00e3o realizada nesta ter\u00e7a-feira (7), o vereador Luciano Almeida comentou sobre o andamento da licita\u00e7\u00e3o para a reconstru\u00e7\u00e3o do viaduto em Alagoinhas e afirmou que o processo ocorreu no dia 31 de mar\u00e7o deste ano, na sede da Companhia de Desenvolvimento Urbano do Estado da Bahia (CONDER). De acordo com o parlamentar, a empresa [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":50207,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[19],"tags":[],"class_list":["post-50206","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bahia"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/50206","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/comments?post=50206"}],"version-history":[{"count":1,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/50206\/revisions"}],"predecessor-version":[{"id":50208,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/50206\/revisions\/50208"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media\/50207"}],"wp:attachment":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media?parent=50206"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/categories?post=50206"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/tags?post=50206"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}