{"id":50235,"date":"2026-04-09T16:26:18","date_gmt":"2026-04-09T19:26:18","guid":{"rendered":"https:\/\/newsinfoco.com.br\/inicio\/?p=50235"},"modified":"2026-04-09T16:26:18","modified_gmt":"2026-04-09T19:26:18","slug":"jusmari-oliveira-critica-prefeito-de-luis-eduardo-magalhaes-por-nao-sustentar-apoio-a-jeronimo","status":"publish","type":"post","link":"https:\/\/newsinfoco.com.br\/inicio\/jusmari-oliveira-critica-prefeito-de-luis-eduardo-magalhaes-por-nao-sustentar-apoio-a-jeronimo\/","title":{"rendered":"Jusmari Oliveira critica prefeito de Lu\u00eds Eduardo Magalh\u00e3es por n\u00e3o sustentar apoio a Jer\u00f4nimo"},"content":{"rendered":"<div class=\"conteudo_post\">\n<p>A deputada estadual Jusmari Oliveira (PSD) criticou, nesta quinta-feira (9), o prefeito de Lu\u00eds Eduardo Magalh\u00e3es, J\u00fanior Marab\u00e1 (PP), que tem se aproximado do pr\u00e9-candidato ao Governo da Bahia, ACM Neto (Uni\u00e3o). Apesar de o apoio ainda n\u00e3o ter sido anunciado publicamente, nos bastidores da pol\u00edtica baiana h\u00e1 especula\u00e7\u00f5es de que o gestor deve apoiar o ex-prefeito de Salvador.<\/p>\n<p>Durante evento no Centro de Opera\u00e7\u00f5es e Intelig\u00eancia da Seguran\u00e7a P\u00fablica, no Centro Administrativo da Bahia, a ex-secret\u00e1ria de Desenvolvimento Urbano (Sedur) comentou o assunto e afirmou que o governo estadual tem realizado investimentos no munic\u00edpio ao lado do governador Jer\u00f4nimo Rodrigues.<\/p><div class=\"newsi-conteudo_19\" id=\"newsi-415593744\"><a href=\"https:\/\/www.instagram.com\/prefeituraalagoinhas?igsh=YzgzdDJ1bWR3aWI4\" aria-label=\"SAVE_20251006_221555\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg\" alt=\"\"  srcset=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg 1140w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-300x52.jpg 300w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1024x177.jpg 1024w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-768x133.jpg 768w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-600x104.jpg 600w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-696x120.jpg 696w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1068x185.jpg 1068w\" sizes=\"(max-width: 1140px) 100vw, 1140px\" width=\"1140\" height=\"197\"   \/><\/a><\/div>\n<p>\u201cN\u00f3s trabalhamos durante anos a realiza\u00e7\u00e3o do aeroporto de Luiz Eduardo Magalh\u00e3es, na hora da inaugura\u00e7\u00e3o, claro \u00e9 a hora do brilho, a\u00ed algu\u00e9m faz a Fake News de que est\u00e1 do lado para poder ir para a inaugura\u00e7\u00e3o e tirar o brilho de quem trabalhou\u201d, disparou Jusmari.<\/p>\n<p>A ex-Sedur tamb\u00e9m destacou obras realizadas pela gest\u00e3o estadual no munic\u00edpio, como a estrada para a comunidade Bela Vista, com investimento de cerca de R$ 40 milh\u00f5es. \u201cN\u00f3s levamos a pra\u00e7a, estamos levando a feira para o bairro Sol Cerrado, pra\u00e7a para o bairro do Jardim Para\u00edso, uma das maiores pra\u00e7as do estado da Bahia que est\u00e1 sendo constru\u00eddo l\u00e1 e \u00e9 claro, o prefeito se movimentou no sentido de tentar levar a fama em cima do trabalho da gente\u201d, disse.<\/p>\n<p>\u201cContinuamos trabalhando, continuamos firme com o governador porque somos leal ao nosso grupo pol\u00edtico, a esse grupo que tem realmente transformado o Oeste da Bahia, transformado a Bahia e quem n\u00e3o \u00e9 verdadeiro n\u00e3o aguenta, quem n\u00e3o \u00e9 verdadeiro, que n\u00e3o consegue fazer o seu intento que \u00e9 distribuir a disc\u00f3rdia entre os leais, n\u00e3o aguenta\u201d, completou.<\/p>\n<div>\n<div>\n<div class=\"trv-player-container\">\n<div class=\"trv-wrapper\">\n<div id=\"br_video_player_c2ef803fc2bd1e2c4319137fa4e0cd9dc3c659f9\" class=\"trvd_video_player trvdinstream\">\n<div class=\"media-player\">\n<div class=\"trv-video\">\n<div id=\"truvid_ima_container78558\" class=\"truvid_ima_container\">\n<div>\n<div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>Jusmari tamb\u00e9m afirmou que nunca teve d\u00favida sobre o lado pol\u00edtico que escolheu. \u201cN\u00f3s estamos do lado de quem trabalha, n\u00f3s estamos do lado de quem eles mesmos reconhecem, trabalhou muito mas n\u00e3o posso votar, ent\u00e3o \u00e9 dif\u00edcil n\u00e9, se voc\u00ea n\u00e3o pode votar em quem trabalha em quem voc\u00ea vai votar, em quem voc\u00ea tem o que, paix\u00e3o, em quem voc\u00ea tem relacionamento pessoal, n\u00f3s n\u00e3o votamos em quem temos relacionamento pessoal, n\u00f3s votamos em quem trabalha, em quem atende as nossas reivindica\u00e7\u00f5es e quem realiza\u201d, pontuou.<\/p>\n<p>\u201cQuem tem atendido nossas reivindica\u00e7\u00f5es e realizado pelo Oeste da Bahia \u00e9 o governador Jer\u00f4nimo, \u00e9 o senador Jaques Wagner, \u00e9 o senador Otto Alencar, \u00e9 esse grupo pol\u00edtico administrativo, atende as nossas e atende as deles tamb\u00e9m, s\u00f3 que n\u00f3s reconhecemos\u201d, finalizou.<\/p>\n<\/div>\n<div id=\"author-info\" class=\"ui items\">\n<div class=\"item\">Bahia.Ba<\/div>\n<\/div>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='Jusmari Oliveira critica prefeito de Lu\u00eds Eduardo Magalh\u00e3es por n\u00e3o sustentar apoio a Jer\u00f4nimo' data-link='https:\/\/newsinfoco.com.br\/inicio\/jusmari-oliveira-critica-prefeito-de-luis-eduardo-magalhaes-por-nao-sustentar-apoio-a-jeronimo\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>A deputada estadual Jusmari Oliveira (PSD) criticou, nesta quinta-feira (9), o prefeito de Lu\u00eds Eduardo Magalh\u00e3es, J\u00fanior Marab\u00e1 (PP), que tem se aproximado do pr\u00e9-candidato ao Governo da Bahia, ACM Neto (Uni\u00e3o). Apesar de o apoio ainda n\u00e3o ter sido anunciado publicamente, nos bastidores da pol\u00edtica baiana h\u00e1 especula\u00e7\u00f5es de que o gestor deve apoiar [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":50236,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[19],"tags":[],"class_list":["post-50235","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bahia"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/50235","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/comments?post=50235"}],"version-history":[{"count":1,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/50235\/revisions"}],"predecessor-version":[{"id":50237,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/50235\/revisions\/50237"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media\/50236"}],"wp:attachment":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media?parent=50235"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/categories?post=50235"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/tags?post=50235"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}