{"id":50303,"date":"2026-04-11T11:58:35","date_gmt":"2026-04-11T14:58:35","guid":{"rendered":"https:\/\/newsinfoco.com.br\/inicio\/?p=50303"},"modified":"2026-04-11T11:58:35","modified_gmt":"2026-04-11T14:58:35","slug":"pt-acionara-tse-contra-videos-com-ia-que-simulam-agressoes-a-mulheres","status":"publish","type":"post","link":"https:\/\/newsinfoco.com.br\/inicio\/pt-acionara-tse-contra-videos-com-ia-que-simulam-agressoes-a-mulheres\/","title":{"rendered":"PT acionar\u00e1 TSE contra v\u00eddeos com IA que simulam agress\u00f5es a mulheres"},"content":{"rendered":"<div class=\"conteudo_post\">\n<p data-start=\"187\" data-end=\"434\">O\u00a0<span class=\"hover:entity-accent entity-underline inline cursor-pointer align-baseline\"><span class=\"whitespace-normal\">Partido dos Trabalhadores<\/span><\/span>\u00a0(PT) informou que vai acionar o\u00a0<span class=\"hover:entity-accent entity-underline inline cursor-pointer align-baseline\"><span class=\"whitespace-normal\">Tribunal Superior Eleitoral<\/span><\/span>\u00a0(TSE) contra a circula\u00e7\u00e3o de v\u00eddeos produzidos com intelig\u00eancia artificial que simulam agress\u00f5es a militantes da sigla nas redes sociais.<\/p>\n<p data-start=\"436\" data-end=\"737\">As publica\u00e7\u00f5es, que t\u00eam sido disseminadas em plataformas como TikTok, Facebook e Instagram, mostram cenas manipuladas em que mulheres aparecem vestindo camisetas do partido e sendo alvo de viol\u00eancia. Em alguns casos, os v\u00eddeos simulam situa\u00e7\u00f5es de \u201cexorcismo\u201d, com agress\u00f5es f\u00edsicas e ofensas verbais.<\/p><div class=\"newsi-conteudo_19\" id=\"newsi-4025759424\"><a href=\"https:\/\/www.instagram.com\/prefeituraalagoinhas?igsh=YzgzdDJ1bWR3aWI4\" aria-label=\"SAVE_20251006_221555\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg\" alt=\"\"  srcset=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg 1140w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-300x52.jpg 300w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1024x177.jpg 1024w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-768x133.jpg 768w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-600x104.jpg 600w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-696x120.jpg 696w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1068x185.jpg 1068w\" sizes=\"(max-width: 1140px) 100vw, 1140px\" width=\"1140\" height=\"197\"   \/><\/a><\/div>\n<div>\n<div>\n<div class=\"trv-player-container\">\n<div class=\"trv-wrapper\">\n<div id=\"br_video_player_6830dc6d70de0da017c4137fa4e0cd9dc3c659f9\" class=\"trvd_video_player trvdinstream\">\n<div class=\"media-player\">\n<div class=\"trv-video\">\n<div id=\"truvid_ima_container45419\" class=\"truvid_ima_container\">\n<div>\n<div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p data-start=\"739\" data-end=\"1109\">De acordo com o secret\u00e1rio de Comunica\u00e7\u00e3o do PT, \u00c9den Valadares, a legenda considera o conte\u00fado grave e pretende buscar a retirada imediata do material. \u201cVamos ainda na manh\u00e3 de hoje, com o nosso Jur\u00eddico, acionar o Tribunal Superior Eleitoral, acionar a Justi\u00e7a Eleitoral sobre essa manipula\u00e7\u00e3o, esse grave ataque ao PT e \u00e0 democracia brasileira como um todo\u201d, afirmou.<\/p>\n<p data-start=\"1111\" data-end=\"1467\">O uso de intelig\u00eancia artificial em conte\u00fados pol\u00edticos tem sido alvo de crescente preocupa\u00e7\u00e3o das autoridades eleitorais. O pr\u00f3prio TSE j\u00e1 vem discutindo medidas para conter a dissemina\u00e7\u00e3o de materiais falsos e manipulados, como os chamados \u201cdeepfakes\u201d, que podem comprometer o debate p\u00fablico e influenciar eleitores<\/p>\n<\/div>\n<div id=\"div-share\">Bahia.Ba<\/div>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='PT acionar\u00e1 TSE contra v\u00eddeos com IA que simulam agress\u00f5es a mulheres' data-link='https:\/\/newsinfoco.com.br\/inicio\/pt-acionara-tse-contra-videos-com-ia-que-simulam-agressoes-a-mulheres\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>O\u00a0Partido dos Trabalhadores\u00a0(PT) informou que vai acionar o\u00a0Tribunal Superior Eleitoral\u00a0(TSE) contra a circula\u00e7\u00e3o de v\u00eddeos produzidos com intelig\u00eancia artificial que simulam agress\u00f5es a militantes da sigla nas redes sociais. As publica\u00e7\u00f5es, que t\u00eam sido disseminadas em plataformas como TikTok, Facebook e Instagram, mostram cenas manipuladas em que mulheres aparecem vestindo camisetas do partido e sendo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":50304,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[21],"tags":[],"class_list":["post-50303","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/50303","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/comments?post=50303"}],"version-history":[{"count":1,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/50303\/revisions"}],"predecessor-version":[{"id":50305,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/50303\/revisions\/50305"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media\/50304"}],"wp:attachment":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media?parent=50303"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/categories?post=50303"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/tags?post=50303"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}