{"id":50306,"date":"2026-04-11T12:04:38","date_gmt":"2026-04-11T15:04:38","guid":{"rendered":"https:\/\/newsinfoco.com.br\/inicio\/?p=50306"},"modified":"2026-04-11T12:04:38","modified_gmt":"2026-04-11T15:04:38","slug":"otto-reage-a-aproximacao-de-coronel-com-flavio-bolsonaro-sempre-foi-bolsonarista","status":"publish","type":"post","link":"https:\/\/newsinfoco.com.br\/inicio\/otto-reage-a-aproximacao-de-coronel-com-flavio-bolsonaro-sempre-foi-bolsonarista\/","title":{"rendered":"Otto reage \u00e0 aproxima\u00e7\u00e3o de Coronel com Fl\u00e1vio Bolsonaro: \u2018Sempre foi bolsonarista\u2019"},"content":{"rendered":"<div class=\"conteudo_post\">\n<div class=\"text-base my-auto mx-auto [--thread-content-margin:var(--thread-content-margin-xs,calc(var(--spacing)*4))] @w-sm\/main:[--thread-content-margin:var(--thread-content-margin-sm,calc(var(--spacing)*6))] @w-lg\/main:[--thread-content-margin:var(--thread-content-margin-lg,calc(var(--spacing)*16))] px-(--thread-content-margin)\">\n<div class=\"[--thread-content-max-width:40rem] @w-lg\/main:[--thread-content-max-width:48rem] mx-auto max-w-(--thread-content-max-width) flex-1 group\/turn-messages focus-visible:outline-hidden relative flex w-full min-w-0 flex-col agent-turn\">\n<div class=\"flex max-w-full flex-col gap-4 grow\">\n<div class=\"min-h-8 text-message relative flex w-full flex-col items-end gap-2 text-start break-words whitespace-normal outline-none keyboard-focused:focus-ring [.text-message+&amp;]:mt-1\" dir=\"auto\" data-message-author-role=\"assistant\" data-message-id=\"dcd03f3c-cc8f-4a95-af7e-63c8549602ec\" data-message-model-slug=\"gpt-5-3\">\n<div class=\"flex w-full flex-col gap-1 empty:hidden\">\n<div class=\"markdown prose dark:prose-invert w-full wrap-break-word light markdown-new-styling\">\n<p data-start=\"0\" data-end=\"283\">Ap\u00f3s o senador\u00a0<span class=\"hover:entity-accent entity-underline inline cursor-pointer align-baseline\"><span class=\"whitespace-normal\">Angelo Coronel (Republicanos)<\/span><\/span>\u00a0\u201cmudar de lado\u201d e romper com a base petista na Bahia, o tamb\u00e9m senador e presidente da Comiss\u00e3o de Constitui\u00e7\u00e3o e Justi\u00e7a,\u00a0<span class=\"hover:entity-accent entity-underline inline cursor-pointer align-baseline\"><span class=\"whitespace-normal\">Otto Alencar (PSD)<\/span><\/span>, reagiu \u00e0s declara\u00e7\u00f5es do ex-aliado e minimizou a mudan\u00e7a de posi\u00e7\u00e3o.<\/p>\n<p data-start=\"285\" data-end=\"492\">Segundo Otto, o movimento n\u00e3o causa surpresa e refor\u00e7a uma postura que, de acordo com ele, j\u00e1 era conhecida. \u201cN\u00e3o me surpreende nem um pouco. Ele (Coronel) \u00e9 bolsonarista desde 2019. Ele \u00e9 isso a\u00ed\u201d, afirmou \u00e0 coluna de Milena Teixeira, do portal Metr\u00f3poles.<\/p><div class=\"newsi-conteudo_19\" id=\"newsi-924957006\"><a href=\"https:\/\/www.instagram.com\/prefeituraalagoinhas?igsh=YzgzdDJ1bWR3aWI4\" aria-label=\"SAVE_20251006_221555\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg\" alt=\"\"  srcset=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg 1140w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-300x52.jpg 300w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1024x177.jpg 1024w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-768x133.jpg 768w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-600x104.jpg 600w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-696x120.jpg 696w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1068x185.jpg 1068w\" sizes=\"(max-width: 1140px) 100vw, 1140px\" width=\"1140\" height=\"197\"   \/><\/a><\/div>\n<p data-start=\"494\" data-end=\"631\" data-is-last-node=\"\" data-is-only-node=\"\">A rela\u00e7\u00e3o entre os dois est\u00e1 rompida desde o fim do ano passado, em meio a acusa\u00e7\u00f5es de tentativa de trai\u00e7\u00e3o envolvendo o comando da CCJ.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"z-0 flex min-h-[46px] justify-start\"><strong>\u00a0Aproxima\u00e7\u00e3o com Fl\u00e1vio Bolsonaro<\/strong><\/div>\n<div>\n<p data-start=\"365\" data-end=\"624\"><span class=\"hover:entity-accent entity-underline inline cursor-pointer align-baseline\"><span class=\"whitespace-normal\">Coronel<\/span><\/span>\u00a0afirmou que decidiu se afastar do grupo pol\u00edtico do PT na Bahia ap\u00f3s alegar ter sido preterido nas articula\u00e7\u00f5es eleitorais do partido ligado ao presidente\u00a0<span class=\"hover:entity-accent entity-underline inline cursor-pointer align-baseline\"><span class=\"whitespace-normal\">Luiz In\u00e1cio Lula da Silva<\/span><\/span>. A<\/p>\n<p data-start=\"626\" data-end=\"791\">Segundo o pol\u00edtico, essa mudan\u00e7a de posi\u00e7\u00e3o o levou a declarar apoio a\u00a0<span class=\"hover:entity-accent entity-underline inline cursor-pointer align-baseline\"><span class=\"whitespace-normal\">Fl\u00e1vio Bolsonaro<\/span><\/span>\u00a0 como pr\u00e9-candidato \u00e0 Presid\u00eancia da Rep\u00fablica.<\/p>\n<p data-start=\"793\" data-end=\"988\">\u201cMeu voto pessoal \u00e9 nele. Sempre me dei bem com ele. \u00c9 meu colega no Senado. J\u00e1 que o PT n\u00e3o me quis, n\u00e3o posso querer eles, n\u00e3o \u00e9? O PT abocanhou as tr\u00eas vagas, tudo pela gan\u00e2ncia deles\u201d, disse.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"author-info\" class=\"ui items\">\n<div class=\"item\">Bahia.Ba<\/div>\n<\/div>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='Otto reage \u00e0 aproxima\u00e7\u00e3o de Coronel com Fl\u00e1vio Bolsonaro: \u2018Sempre foi bolsonarista\u2019' data-link='https:\/\/newsinfoco.com.br\/inicio\/otto-reage-a-aproximacao-de-coronel-com-flavio-bolsonaro-sempre-foi-bolsonarista\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Ap\u00f3s o senador\u00a0Angelo Coronel (Republicanos)\u00a0\u201cmudar de lado\u201d e romper com a base petista na Bahia, o tamb\u00e9m senador e presidente da Comiss\u00e3o de Constitui\u00e7\u00e3o e Justi\u00e7a,\u00a0Otto Alencar (PSD), reagiu \u00e0s declara\u00e7\u00f5es do ex-aliado e minimizou a mudan\u00e7a de posi\u00e7\u00e3o. Segundo Otto, o movimento n\u00e3o causa surpresa e refor\u00e7a uma postura que, de acordo com ele, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":50307,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[19],"tags":[],"class_list":["post-50306","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bahia"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/50306","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/comments?post=50306"}],"version-history":[{"count":1,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/50306\/revisions"}],"predecessor-version":[{"id":50308,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/50306\/revisions\/50308"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media\/50307"}],"wp:attachment":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media?parent=50306"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/categories?post=50306"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/tags?post=50306"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}