{"id":50309,"date":"2026-04-11T12:14:48","date_gmt":"2026-04-11T15:14:48","guid":{"rendered":"https:\/\/newsinfoco.com.br\/inicio\/?p=50309"},"modified":"2026-04-11T12:14:48","modified_gmt":"2026-04-11T15:14:48","slug":"inmet-emite-alerta-laranja-para-chuvas-intensas-em-cidades-da-bahia","status":"publish","type":"post","link":"https:\/\/newsinfoco.com.br\/inicio\/inmet-emite-alerta-laranja-para-chuvas-intensas-em-cidades-da-bahia\/","title":{"rendered":"Inmet emite alerta laranja para chuvas intensas em cidades da Bahia"},"content":{"rendered":"<div class=\"conteudo_post\">\n<p data-start=\"177\" data-end=\"468\">Cerca de 27 munic\u00edpios da\u00a0<span class=\"hover:entity-accent entity-underline inline cursor-pointer align-baseline\"><span class=\"whitespace-normal\">Bahia<\/span><\/span>\u00a0est\u00e3o sob alerta laranja devido \u00e0s fortes chuvas previstas para este fim de semana. O aviso foi emitido pelo\u00a0<span class=\"hover:entity-accent entity-underline inline cursor-pointer align-baseline\"><span class=\"whitespace-normal\">Instituto Nacional de Meteorologia<\/span><\/span>\u00a0(Inmet) e abrange principalmente cidades das regi\u00f5es sul e centro-sul do estado.<\/p>\n<p data-start=\"470\" data-end=\"763\">De acordo com o \u00f3rg\u00e3o, o volume de chuva pode variar entre 30 e 60 mil\u00edmetros por hora, podendo chegar a at\u00e9 100 mil\u00edmetros em um \u00fanico dia. Al\u00e9m disso, os ventos podem atingir velocidades entre 60 e 100 km\/h, o que aumenta o risco de queda de \u00e1rvores, destelhamento de im\u00f3veis e outros danos.<\/p><div class=\"newsi-conteudo_19\" id=\"newsi-3646817778\"><a href=\"https:\/\/www.instagram.com\/prefeituraalagoinhas?igsh=YzgzdDJ1bWR3aWI4\" aria-label=\"SAVE_20251006_221555\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg\" alt=\"\"  srcset=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg 1140w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-300x52.jpg 300w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1024x177.jpg 1024w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-768x133.jpg 768w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-600x104.jpg 600w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-696x120.jpg 696w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1068x185.jpg 1068w\" sizes=\"(max-width: 1140px) 100vw, 1140px\" width=\"1140\" height=\"197\"   \/><\/a><\/div>\n<div>\n<div>\n<div class=\"trv-player-container\">\n<div class=\"trv-wrapper\">\n<div id=\"br_video_player_0647534ed7223c44f3d6137fa4e0cd9dc3c659f9\" class=\"trvd_video_player trvdinstream\">\n<div class=\"media-player\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p data-start=\"765\" data-end=\"1047\">O alerta \u00e9 v\u00e1lido at\u00e9 as 23h59 deste s\u00e1bado (11), podendo ser prorrogado para alguns munic\u00edpios. A recomenda\u00e7\u00e3o \u00e9 que a popula\u00e7\u00e3o fique atenta a poss\u00edveis alagamentos e, em caso de emerg\u00eancia, entre em contato com a Defesa Civil pelo n\u00famero 199 ou com o Corpo de Bombeiros pelo 193.<\/p>\n<h4 data-start=\"1049\" data-end=\"1082\"><strong data-start=\"1049\" data-end=\"1082\">Confira as cidades em alerta:<\/strong><\/h4>\n<p data-start=\"1084\" data-end=\"1417\" data-is-last-node=\"\" data-is-only-node=\"\">Alcoba\u00e7a<br data-start=\"1092\" data-end=\"1095\" \/>Belmonte<br data-start=\"1103\" data-end=\"1106\" \/>Canavieiras<br data-start=\"1117\" data-end=\"1120\" \/>Caravelas<br data-start=\"1129\" data-end=\"1132\" \/>Eun\u00e1polis<br data-start=\"1141\" data-end=\"1144\" \/>Guaratinga<br data-start=\"1154\" data-end=\"1157\" \/>Ibirapu\u00e3<br data-start=\"1165\" data-end=\"1168\" \/>Itabela<br data-start=\"1175\" data-end=\"1178\" \/>Itagimirim<br data-start=\"1188\" data-end=\"1191\" \/>Itamaraju<br data-start=\"1200\" data-end=\"1203\" \/>Itanh\u00e9m<br data-start=\"1210\" data-end=\"1213\" \/>Itapebi<br data-start=\"1220\" data-end=\"1223\" \/>Itarantim<br data-start=\"1232\" data-end=\"1235\" \/>Jucuru\u00e7u<br data-start=\"1243\" data-end=\"1246\" \/>Lajed\u00e3o<br data-start=\"1253\" data-end=\"1256\" \/>Macarani<br data-start=\"1264\" data-end=\"1267\" \/>Maiquinique<br data-start=\"1278\" data-end=\"1281\" \/>Mascote<br data-start=\"1288\" data-end=\"1291\" \/>Medeiros Neto<br data-start=\"1304\" data-end=\"1307\" \/>Mucuri<br data-start=\"1313\" data-end=\"1316\" \/>Nova Vi\u00e7osa<br data-start=\"1327\" data-end=\"1330\" \/>Porto Seguro<br data-start=\"1342\" data-end=\"1345\" \/>Potiragu\u00e1<br data-start=\"1354\" data-end=\"1357\" \/>Prado<br data-start=\"1362\" data-end=\"1365\" \/>Santa Cruz Cabr\u00e1lia<br data-start=\"1384\" data-end=\"1387\" \/>Teixeira de Freitas<br data-start=\"1406\" data-end=\"1409\" \/>Vereda<\/p>\n<\/div>\n<div id=\"div-share\">Bahia.Ba<\/div>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='Inmet emite alerta laranja para chuvas intensas em cidades da Bahia' data-link='https:\/\/newsinfoco.com.br\/inicio\/inmet-emite-alerta-laranja-para-chuvas-intensas-em-cidades-da-bahia\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Cerca de 27 munic\u00edpios da\u00a0Bahia\u00a0est\u00e3o sob alerta laranja devido \u00e0s fortes chuvas previstas para este fim de semana. O aviso foi emitido pelo\u00a0Instituto Nacional de Meteorologia\u00a0(Inmet) e abrange principalmente cidades das regi\u00f5es sul e centro-sul do estado. De acordo com o \u00f3rg\u00e3o, o volume de chuva pode variar entre 30 e 60 mil\u00edmetros por hora, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":50310,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[19],"tags":[],"class_list":["post-50309","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bahia"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/50309","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/comments?post=50309"}],"version-history":[{"count":1,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/50309\/revisions"}],"predecessor-version":[{"id":50311,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/50309\/revisions\/50311"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media\/50310"}],"wp:attachment":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media?parent=50309"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/categories?post=50309"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/tags?post=50309"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}