{"id":5057,"date":"2018-06-09T17:26:28","date_gmt":"2018-06-09T20:26:28","guid":{"rendered":"http:\/\/newsinfoco.com.br\/?p=5057"},"modified":"2018-06-09T17:26:28","modified_gmt":"2018-06-09T20:26:28","slug":"pt-baiano-reforca-apoio-a-candidatura-de-lula","status":"publish","type":"post","link":"https:\/\/newsinfoco.com.br\/inicio\/pt-baiano-reforca-apoio-a-candidatura-de-lula\/","title":{"rendered":"PT baiano refor\u00e7a apoio \u00e0 candidatura de Lula"},"content":{"rendered":"<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">O PT da Bahia refor\u00e7ou o apoio \u00e0 postula\u00e7\u00e3o do ex-presidente Luiz In\u00e1cio Lula da Silva (PT) ao Pal\u00e1cio do Planalto ontem, durante o lan\u00e7amento oficial da pr\u00e9-candidatura do petista, em Contagem, na regi\u00e3o metropolitana de Belo Horizonte. O evento teve a presen\u00e7a do presidente do partido na Bahia, Everaldo Anuncia\u00e7\u00e3o, e do ex-governador Jaques Wagner e deputados da sigla. \u201c\u00c9 um ato para reafirmar o que o povo brasileiro est\u00e1 dizendo. O povo quer que o Brasil volte a se desenvolver. S\u00f3 Lula tem condi\u00e7\u00f5es fazer isso. Al\u00e9m disso, queremos tamb\u00e9m a liberdade de Lula, que tem sido perseguido politicamente\u201d, afirmou Everaldo, ao ressaltar que o PT vai registrar a candidatura do ex-presidente no dia 15 de agosto, \u00faltimo prazo para a inscri\u00e7\u00e3o definido pelo Tribunal Superior Eleitoral (TSE).\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">O presidente do PT baiano disse que a agremia\u00e7\u00e3o n\u00e3o definiu o vice na chapa, mas defendeu que o integrante da composi\u00e7\u00e3o seja \u201cde outro partido que n\u00e3o seja do PT\u201d. Nos bastidores, parte dos petistas quer que seja um membro da sigla para que substitua Lula, caso a candidatura seja indeferida pela Corte Eleitoral. O nome do ex-ministro das Rela\u00e7\u00f5es Exteriores, Celso Amorim, j\u00e1 foi cotado para o posto.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Lula est\u00e1 preso desde o dia 7 de abril na Superintend\u00eancia da Pol\u00edcia Federal em Curitiba, ap\u00f3s ser condenado a 12 anos e um m\u00eas, em segunda inst\u00e2ncia por corrup\u00e7\u00e3o passiva e lavagem de dinheiro no caso do triplex. O petista deve ter a candidatura indeferida com base na Lei da Ficha Limpa. O PT, no entanto, tenta manter viva a ideia de que o ex-presidente \u00e9 o candidato do PT. Desde o ano passado, Lula aparece como l\u00edder nas pesquisas de inten\u00e7\u00e3o de voto, prefer\u00eancia que se mant\u00e9m mesmo depois de sua pris\u00e3o. Na Bahia, o ex-chefe do Pal\u00e1cio do Planalto teria 43,4% das inten\u00e7\u00f5es de votos, se fosse candidato, conforme levantamento do instituto Paran\u00e1 Pesquisas divulgado na semana passada. Ontem, nas redes sociais, o ex-governador Jaques Wagner voltou a condenar a pris\u00e3o do aliado. \u201cO presidente Lula e sua fam\u00edlia tiveram as vidas devassadas durante anos. H\u00e1 60 dias, ele est\u00e1 injustamente preso. E mesmo depois de todo esse tempo seus acusadores foram incapazes de apresentar uma prova, uma evid\u00eancia sequer, de que tenha cometido qualquer crime\u201d, afirmou, em sua conta no Twitter.<\/span><\/p><div class=\"newsi-conteudo_19\" id=\"newsi-3223705947\"><a href=\"https:\/\/www.instagram.com\/prefeituraalagoinhas?igsh=YzgzdDJ1bWR3aWI4\" aria-label=\"SAVE_20251006_221555\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg\" alt=\"\"  srcset=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg 1140w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-300x52.jpg 300w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1024x177.jpg 1024w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-768x133.jpg 768w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-600x104.jpg 600w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-696x120.jpg 696w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1068x185.jpg 1068w\" sizes=\"(max-width: 1140px) 100vw, 1140px\" width=\"1140\" height=\"197\"   \/><\/a><\/div>\n<p>&nbsp;<\/p>\n<h6 style=\"text-align: right;\">Por Rodrigo Daniel Silva<\/h6>\n<h6 style=\"text-align: right;\">Fonte:trbn<\/h6>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='PT baiano refor\u00e7a apoio \u00e0 candidatura de Lula' data-link='https:\/\/newsinfoco.com.br\/inicio\/pt-baiano-reforca-apoio-a-candidatura-de-lula\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>O PT da Bahia refor\u00e7ou o apoio \u00e0 postula\u00e7\u00e3o do ex-presidente Luiz In\u00e1cio Lula da Silva (PT) ao Pal\u00e1cio do Planalto ontem, durante o lan\u00e7amento oficial da pr\u00e9-candidatura do petista, em Contagem, na regi\u00e3o metropolitana de Belo Horizonte. O evento teve a presen\u00e7a do presidente do partido na Bahia, Everaldo Anuncia\u00e7\u00e3o, e do ex-governador Jaques [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5059,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[19],"tags":[],"class_list":["post-5057","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bahia"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/5057","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/comments?post=5057"}],"version-history":[{"count":0,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/5057\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media\/5059"}],"wp:attachment":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media?parent=5057"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/categories?post=5057"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/tags?post=5057"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}