{"id":50871,"date":"2026-05-13T12:45:18","date_gmt":"2026-05-13T15:45:18","guid":{"rendered":"https:\/\/newsinfoco.com.br\/inicio\/?p=50871"},"modified":"2026-05-13T12:45:18","modified_gmt":"2026-05-13T15:45:18","slug":"mais-carros-fumace-reforcam-o-combate-ao-aedes-aegypti-em-alagoinhas","status":"publish","type":"post","link":"https:\/\/newsinfoco.com.br\/inicio\/mais-carros-fumace-reforcam-o-combate-ao-aedes-aegypti-em-alagoinhas\/","title":{"rendered":"Mais carros fumac\u00ea refor\u00e7am o combate ao Aedes aegypti em Alagoinhas"},"content":{"rendered":"<p>A Prefeitura de Alagoinhas segue intensificando as a\u00e7\u00f5es de combate ao mosquito Aedes aegypti. Nesta quarta-feira (13), o trabalho realizado pela Secretaria Municipal de Sa\u00fade (SESAU) ganhou um refor\u00e7o importante: o munic\u00edpio recebeu mais dois carros fumac\u00ea, totalizando agora oito ve\u00edculos de nebuliza\u00e7\u00e3o veicular (UBV pesado) em circula\u00e7\u00e3o na cidade.<\/p>\n<p>Os ve\u00edculos percorrer\u00e3o os bairros que apresentam maior incid\u00eancia de casos e altos \u00edndices de infesta\u00e7\u00e3o. Entre as localidades contempladas est\u00e3o: Jardim Petrolar, Conjunto Dom Jos\u00e9 Cornelis, Parque Floresta, Parque Regente, Conjunto Pinto Aguiar, Brasilinha, Parque Alagoinhas, Conjunto Alagoinhas III (Urbis\/Rua Catu), Parque S\u00e3o Francisco, Urupiara, Conjunto Bom Viver, Parque Vit\u00f3ria, Jardim Pedro Braga, Teres\u00f3polis, Vila dos Laranjais, Santo Ant\u00f4nio, Santa Terezinha, Alecrim, Jardim Santa Terezinha, Alagoinhas Velha, Cavada, Jardim Imperial, Inocoop I e II, Centro, Silva Jardim, Baixa da Candeia, Baixa do Corte, Santa Isabel, \u00c1guas do Viver, Vila S\u00e3o Pedro, Barreiro de Baixo e Barreiro de Cima.<\/p><div class=\"newsi-conteudo_19\" id=\"newsi-2167820714\"><a href=\"https:\/\/www.instagram.com\/prefeituraalagoinhas?igsh=YzgzdDJ1bWR3aWI4\" aria-label=\"SAVE_20251006_221555\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg\" alt=\"\"  srcset=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg 1140w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-300x52.jpg 300w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1024x177.jpg 1024w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-768x133.jpg 768w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-600x104.jpg 600w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-696x120.jpg 696w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1068x185.jpg 1068w\" sizes=\"(max-width: 1140px) 100vw, 1140px\" width=\"1140\" height=\"197\"   \/><\/a><\/div>\n<p>A chegada dos novos carros soma-se a outras estrat\u00e9gias j\u00e1 em curso, como a atua\u00e7\u00e3o de mais de 50 agentes de combate \u00e0s endemias. Esses profissionais cobrem cerca de 1.700 quarteir\u00f5es com visitas domiciliares, elimina\u00e7\u00e3o de focos e aplica\u00e7\u00e3o de inseticidas com bombas costais, al\u00e9m de promoverem a\u00e7\u00f5es educativas nas escolas da rede municipal.<\/p>\n<div align=\"right\"><\/div>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='Mais carros fumac\u00ea refor\u00e7am o combate ao Aedes aegypti em Alagoinhas' data-link='https:\/\/newsinfoco.com.br\/inicio\/mais-carros-fumace-reforcam-o-combate-ao-aedes-aegypti-em-alagoinhas\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>A Prefeitura de Alagoinhas segue intensificando as a\u00e7\u00f5es de combate ao mosquito Aedes aegypti. Nesta quarta-feira (13), o trabalho realizado pela Secretaria Municipal de Sa\u00fade (SESAU) ganhou um refor\u00e7o importante: o munic\u00edpio recebeu mais dois carros fumac\u00ea, totalizando agora oito ve\u00edculos de nebuliza\u00e7\u00e3o veicular (UBV pesado) em circula\u00e7\u00e3o na cidade. Os ve\u00edculos percorrer\u00e3o os bairros [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":50872,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[38,167],"tags":[],"class_list":["post-50871","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alagoinhas-e-regiao","category-exclusivas"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/50871","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/comments?post=50871"}],"version-history":[{"count":1,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/50871\/revisions"}],"predecessor-version":[{"id":50873,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/50871\/revisions\/50873"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media\/50872"}],"wp:attachment":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media?parent=50871"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/categories?post=50871"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/tags?post=50871"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}